{"id":104235,"date":"2025-04-06T17:58:57","date_gmt":"2025-04-06T23:58:57","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=104235"},"modified":"2025-04-06T17:58:59","modified_gmt":"2025-04-06T23:58:59","slug":"reafirma-gobierno-estatal-compromiso-con-la-gestion-publica","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/reafirma-gobierno-estatal-compromiso-con-la-gestion-publica\/","title":{"rendered":"Reafirma gobierno estatal compromiso con la gesti\u00f3n p\u00fablica"},"content":{"rendered":"\n<p><br>\u2022 San Luis Potos\u00ed particip\u00f3 en la Asamblea Ordinaria de la Regi\u00f3n Centro Pac\u00edfico de la Comisi\u00f3n Permanente de Contralores Estados\u2013Federaci\u00f3n.<\/p>\n\n\n\n<p>Para fortalecer las pol\u00edticas p\u00fablicas acorde a los lineamientos federales en materia de control interno, fiscalizaci\u00f3n, prevenci\u00f3n, detecci\u00f3n, disuasi\u00f3n de hechos de corrupci\u00f3n y mejora de la administraci\u00f3n p\u00fablica, San Luis Potos\u00ed particip\u00f3 en la Asamblea de la Comisi\u00f3n Permanente de Contralores Estados\u2013Federaci\u00f3n (CPCE-F), con lo que promueve la visi\u00f3n estatal en torno a la transparencia y la rendici\u00f3n de cuentas como lo ha instruido el Gobernador Ricardo Gallardo Cardona.<br>As\u00ed lo afirm\u00f3 el contralor general del Estado Sergio Arturo Agui\u00f1aga Mu\u00f1iz, quien destac\u00f3 que la asamblea celebrada en Xochitepec, Morelos, abord\u00f3 temas como los instrumentos para las evaluaciones de confianza o integridad a las personas servidoras p\u00fablicas, dificultades en las declaraciones patrimoniales, mecanismos de prevenci\u00f3n a la corrupci\u00f3n y fomento a la cultura de la legalidad y \u00e9tica de las personas servidoras p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 San Luis Potos\u00ed particip\u00f3 en la Asamblea Ordinaria de la Regi\u00f3n Centro Pac\u00edfico de la Comisi\u00f3n Permanente de Contralores Estados\u2013Federaci\u00f3n. Para fortalecer las pol\u00edticas p\u00fablicas acorde a los lineamientos federales en materia de control interno, fiscalizaci\u00f3n, prevenci\u00f3n, detecci\u00f3n, disuasi\u00f3n de hechos de corrupci\u00f3n y &hellip; <\/p>\n","protected":false},"author":1,"featured_media":104236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,25,82,14,87,86,67,7,78,62,4,44,60,30,31,59,42,53,57,43,32],"tags":[],"class_list":["post-104235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-aquismon","category-axtla","category-caneros","category-cardenas","category-cedral","category-charcas","category-ciudad","category-ciudad-del-maiz","category-ciudad-fernandez","category-inicio","category-matehuala","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamazunchale","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/104235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=104235"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/104235\/revisions"}],"predecessor-version":[{"id":104237,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/104235\/revisions\/104237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/104236"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=104235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=104235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=104235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}