{"id":107654,"date":"2025-08-24T22:19:47","date_gmt":"2025-08-25T04:19:47","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=107654"},"modified":"2025-08-24T22:19:48","modified_gmt":"2025-08-25T04:19:48","slug":"inmuvi-confirma-que-personal-de-insus-trabaja-en-proceso-de-regularizacion-de-colonia-plan-de-ayala-nuevas-generaciones","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/inmuvi-confirma-que-personal-de-insus-trabaja-en-proceso-de-regularizacion-de-colonia-plan-de-ayala-nuevas-generaciones\/","title":{"rendered":"INMUVI confirma que personal de INSUS trabaja en proceso de regularizaci\u00f3n de colonia Plan de Ayala Nuevas Generaciones"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Atendiendo la inquietud de las familias de las colonias Buenos Aires y Plan de Ayala, el Instituto Municipal de la Vivienda (INMUVI), a cargo de Liliana Guadalupe Flores Almaz\u00e1n, informa que personal del Instituto Nacional del Suelo Sustentable (INSUS) se encuentra laborando en el sector de Plan de Ayala, como parte de los trabajos coordinados entre instituciones de gobierno para que muchas familias que hoy se encuentran en posesi\u00f3n irregular de un terreno puedan lograr, despu\u00e9s de varios a\u00f1os, contar con sus escrituras.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que, gracias a la comunicaci\u00f3n permanente entre INMUVI e INSUS, ser\u00e1 personal de este \u00faltimo organismo el encargado de llevar a cabo los trabajos de campo necesarios para la regularizaci\u00f3n, destacando la importancia de seguir paso a paso los procedimientos que este proceso conlleva.<\/p>\n\n\n\n<p>Por parte del H. Ayuntamiento de Ciudad Valles, se reafirma el compromiso y el convenio celebrado con INSUS para respaldar los procesos de regularizaci\u00f3n y dar certeza jur\u00eddica al patrimonio de las familias.<\/p>\n\n\n\n<p>Asimismo, se constat\u00f3 que personal de INSUS ya se encuentra realizando labores en la colonia Plan de Ayala, identific\u00e1ndose debidamente ante los habitantes para dar seguimiento a los trabajos de regularizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atendiendo la inquietud de las familias de las colonias Buenos Aires y Plan de Ayala, el Instituto Municipal de la Vivienda (INMUVI), a cargo de Liliana Guadalupe Flores Almaz\u00e1n, informa que personal del Instituto Nacional del Suelo Sustentable (INSUS) se encuentra laborando en el sector &hellip; <\/p>\n","protected":false},"author":1,"featured_media":107655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,14,28,29,7,15,16,4],"tags":[],"class_list":["post-107654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-caneros","category-cnc","category-cnpr","category-ciudad","category-ganaderos","category-ingenios","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/107654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=107654"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/107654\/revisions"}],"predecessor-version":[{"id":107656,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/107654\/revisions\/107656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/107655"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=107654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=107654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=107654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}