{"id":110405,"date":"2025-12-23T06:57:15","date_gmt":"2025-12-23T12:57:15","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=110405"},"modified":"2025-12-23T06:57:17","modified_gmt":"2025-12-23T12:57:17","slug":"con-mas-de-70-cursos-disponibles-se-invita-a-jovenes-y-adultos-a-desarrollar-su-talento-en-danza-teatro-musica-artes-visuales-y-literatura-inscripciones-presenciales-a-partir-del-5-de-enero","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/con-mas-de-70-cursos-disponibles-se-invita-a-jovenes-y-adultos-a-desarrollar-su-talento-en-danza-teatro-musica-artes-visuales-y-literatura-inscripciones-presenciales-a-partir-del-5-de-enero\/","title":{"rendered":"Con m\u00e1s de 70 cursos disponibles se invita a j\u00f3venes y adultos a desarrollar su talento en danza, teatro, m\u00fasica, artes visuales y literatura. Inscripciones presenciales a partir del 5 de enero."},"content":{"rendered":"\n<p>EN ENERO EL IPBA INICIA INSCRIPCIONES 2026<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<p>El Instituto Potosino de Bellas Artes (IPBA) abre inscripciones para el semestre enero-junio de 2026, para seguir brindando acceso a las y los potosinos a la educaci\u00f3n art\u00edstica y cultural, con el respaldo sin l\u00edmites que el Gobernador Ricardo Gallardo Cardona, brinda a nuevos artistas y creadores.<br>El plan educativo contempla m\u00e1s de 70 cursos en \u00e1reas como: Danza, Teatro, M\u00fasica, Literatura, Artes Visuales y Fotograf\u00eda, con opciones dise\u00f1adas para distintos niveles, edades y horarios. La oferta incluye disciplinas como danza, teatro, pintura, escultura, serigraf\u00eda, entre otras alternativas que fomentan la creatividad y el desarrollo art\u00edstico.<br>Las inscripciones iniciar\u00e1n el lunes 5 de enero de 2026 de manera presencial en las instalaciones del Instituto, ubicadas en avenida Universidad esquina con Constituci\u00f3n de 8:30 a 18:30 horas. Los detalles sobre cursos, costos y requisitos pueden consultarse en el siguiente enlace: https:\/\/tinyurl.com\/yeyk4pve y en las redes sociales oficiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EN ENERO EL IPBA INICIA INSCRIPCIONES 2026 El Instituto Potosino de Bellas Artes (IPBA) abre inscripciones para el semestre enero-junio de 2026, para seguir brindando acceso a las y los potosinos a la educaci\u00f3n art\u00edstica y cultural, con el respaldo sin l\u00edmites que el Gobernador &hellip; <\/p>\n","protected":false},"author":1,"featured_media":110406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,92,91,25,89,82,14,29,87,86,67,7,78,62,56,15,55,81,16,4,73,44,26,74,10,12,60,30,31,59,42,53,57,43,32],"tags":[],"class_list":["post-110405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-ahualulco","category-alaquines","category-aquismon","category-armadillo","category-axtla","category-caneros","category-cnpr","category-cardenas","category-cedral","category-charcas","category-ciudad","category-ciudad-del-maiz","category-ciudad-fernandez","category-el-naranjo","category-ganaderos","category-guadalcazar","category-huehuetlan","category-ingenios","category-inicio","category-lagunillas","category-matehuala","category-matlapa","category-mexquitic","category-municipios","category-nacional","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamazunchale","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=110405"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110405\/revisions"}],"predecessor-version":[{"id":110407,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110405\/revisions\/110407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/110406"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=110405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=110405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=110405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}