{"id":110408,"date":"2025-12-23T06:59:24","date_gmt":"2025-12-23T12:59:24","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=110408"},"modified":"2025-12-23T06:59:26","modified_gmt":"2025-12-23T12:59:26","slug":"el-gobierno-del-estado-impulsa-acciones-sostenibles-que-fortalecen-la-dignidad-la-salud-y-la-autonomia-de-las-mujeres-en-san-luis-potosi","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/el-gobierno-del-estado-impulsa-acciones-sostenibles-que-fortalecen-la-dignidad-la-salud-y-la-autonomia-de-las-mujeres-en-san-luis-potosi\/","title":{"rendered":"El Gobierno del Estado impulsa acciones sostenibles que fortalecen la dignidad, la salud y la autonom\u00eda de las mujeres en San Luis Potos\u00ed."},"content":{"rendered":"\n<p>M\u00c1S DE 27 MIL MUJERES Y ADOLESCENTES RECIBEN KITS MENSTRUALES<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><\/li>\n<\/ul>\n\n\n\n<p>Con el respaldo del Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona, el Sistema Estatal para el Desarrollo Integral de la Familia (DIF) ha entregado m\u00e1s de 27 mil kits menstruales a mujeres y adolescentes en cientos de comunidades, y ha proporcionado apoyos funcionales como sillas de ruedas, bastones y andaderas, llevando atenci\u00f3n integral y cercana a la poblaci\u00f3n m\u00e1s vulnerable.<br>La dependencia Estatal afirm\u00f3 que la campa\u00f1a \u201cCaminemos de la mano por una Menstruaci\u00f3n Digna\u201d, a cuatro a\u00f1os de su lanzamiento, refleja el compromiso sin l\u00edmites del Gobierno del Estado con las mujeres y sus necesidades hist\u00f3ricamente invisibilizadas.<br>El programa garantiza productos de higiene reutilizables y de calidad, e incluye informaci\u00f3n sobre autocuidado y salud menstrual, promoviendo un enfoque sustentable y respetuoso. As\u00ed se fortalece el desarrollo de las mujeres potosinas y se avanza hacia una entidad m\u00e1s justa e inclusiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00c1S DE 27 MIL MUJERES Y ADOLESCENTES RECIBEN KITS MENSTRUALES Con el respaldo del Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona, el Sistema Estatal para el Desarrollo Integral de la Familia (DIF) ha entregado m\u00e1s de 27 mil kits menstruales a mujeres y adolescentes &hellip; <\/p>\n","protected":false},"author":1,"featured_media":110409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,92,91,25,89,82,14,28,67,7,78,62,56,15,55,81,16,4,73,44,26,74,10,12,60,30,31,59,42,53,57,43,32],"tags":[],"class_list":["post-110408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-ahualulco","category-alaquines","category-aquismon","category-armadillo","category-axtla","category-caneros","category-cnc","category-charcas","category-ciudad","category-ciudad-del-maiz","category-ciudad-fernandez","category-el-naranjo","category-ganaderos","category-guadalcazar","category-huehuetlan","category-ingenios","category-inicio","category-lagunillas","category-matehuala","category-matlapa","category-mexquitic","category-municipios","category-nacional","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamazunchale","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=110408"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110408\/revisions"}],"predecessor-version":[{"id":110410,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110408\/revisions\/110410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/110409"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=110408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=110408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=110408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}