{"id":110451,"date":"2025-12-26T07:40:38","date_gmt":"2025-12-26T13:40:38","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=110451"},"modified":"2025-12-26T07:40:40","modified_gmt":"2025-12-26T13:40:40","slug":"metrored-supera-los-17-millones-de-viajes-gratuitos","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/metrored-supera-los-17-millones-de-viajes-gratuitos\/","title":{"rendered":"METRORED supera los 17 millones de viajes gratuitos"},"content":{"rendered":"\n<p>San Luis Potos\u00ed reafirma su liderazgo en movilidad urbana con MetroRed, que ha superado los 17 millones de viajes gratuitos. Este sistema, rescatado del abandono de la herencia maldita refleja el compromiso del Gobernador Ricardo Gallardo Cardona de ofrecer un transporte moderno, seguro y accesible para todas y todos.<br>Con cuatro l\u00edneas activas en la zona metropolitana y otra en Ciudad Valles, MetroRed permite que estudiantes, trabajadores, mujeres, adultos mayores y familias se trasladen sin costo en unidades inclusivas y rutas estrat\u00e9gicas. Adem\u00e1s, el sistema gener\u00f3 un ahorro superior a 160 millones de pesos para las familias potosinas, siendo el \u00fanico transporte gratuito de su tipo en M\u00e9xico.<br>El impacto social es significativo: no solo reduce el gasto diario en transporte, sino que tambi\u00e9n promueve la igualdad de oportunidades y la inclusi\u00f3n, beneficiando especialmente a quienes m\u00e1s lo necesitan.<br>El MetroRed se expandir\u00e1 al Altiplano y la Regi\u00f3n Media, conectando municipios clave como Matehuala, Rioverde y Ciudad Fern\u00e1ndez, consolidando a San Luis Potos\u00ed como referente nacional en movilidad sustentable, gratuita y socialmente responsable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Luis Potos\u00ed reafirma su liderazgo en movilidad urbana con MetroRed, que ha superado los 17 millones de viajes gratuitos. Este sistema, rescatado del abandono de la herencia maldita refleja el compromiso del Gobernador Ricardo Gallardo Cardona de ofrecer un transporte moderno, seguro y accesible &hellip; <\/p>\n","protected":false},"author":1,"featured_media":110452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,92,91,25,89,82,14,28,29,87,86,67,7,78,62,56,15,55,81,16,4,73,44,26,74,10,12,60,30,31,59,42,53,57,43,32],"tags":[],"class_list":["post-110451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-ahualulco","category-alaquines","category-aquismon","category-armadillo","category-axtla","category-caneros","category-cnc","category-cnpr","category-cardenas","category-cedral","category-charcas","category-ciudad","category-ciudad-del-maiz","category-ciudad-fernandez","category-el-naranjo","category-ganaderos","category-guadalcazar","category-huehuetlan","category-ingenios","category-inicio","category-lagunillas","category-matehuala","category-matlapa","category-mexquitic","category-municipios","category-nacional","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamazunchale","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=110451"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110451\/revisions"}],"predecessor-version":[{"id":110453,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/110451\/revisions\/110453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/110452"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=110451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=110451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=110451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}