{"id":112410,"date":"2026-03-26T06:12:12","date_gmt":"2026-03-26T12:12:12","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=112410"},"modified":"2026-03-26T06:12:14","modified_gmt":"2026-03-26T12:12:14","slug":"el-gobierno-municipal-de-ciudad-valles-y-la-secretaria-de-gobernacion-invitan-a-la-ciudadania-a-participar-en-la-jornada-de-paz","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/el-gobierno-municipal-de-ciudad-valles-y-la-secretaria-de-gobernacion-invitan-a-la-ciudadania-a-participar-en-la-jornada-de-paz\/","title":{"rendered":"El Gobierno Municipal de Ciudad Valles y la Secretar\u00eda de Gobernaci\u00f3n, invitan a la ciudadan\u00eda a participar en la Jornada de Paz."},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>\ud83d\udcc6 D\u00eda: Jueves 26 de Marzo<br>\ud83d\udccd Lugar: Canchas del Fracc. El Consuelo<br>\ud83d\udd5c Horario: 09:00 a 16:00 horas<\/p>\n\n\n\n<p>\ud83d\udd4a\ufe0f La Jornada de Paz es una iniciativa impulsada por la Presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, que acerca servicios, orientaci\u00f3n y atenci\u00f3n directa a la poblaci\u00f3n mediante la coordinaci\u00f3n entre los tres \u00f3rdenes de gobierno.<\/p>\n\n\n\n<p>\u2705 Participar\u00e1n dependencias federales como INFONAVIT, CONAVI y Bienestar, as\u00ed como \u00e1reas del H. Ayuntamiento de Ciudad Valles, como el Registro Civil, la Instancia Municipal de la Mujer (IMM), el Instituto Municipal de la Vivienda (INMUVI), entre otras.<\/p>\n\n\n\n<p>Con estas acciones, el Gobierno Municipal reafirma el compromiso del Alcalde David Armando Medina Salazar de trabajar en coordinaci\u00f3n con la Federaci\u00f3n y el Estado para acercar servicios, fortalecer la atenci\u00f3n ciudadana y generar bienestar en los sectores que m\u00e1s lo necesitan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcc6 D\u00eda: Jueves 26 de Marzo\ud83d\udccd Lugar: Canchas del Fracc. El Consuelo\ud83d\udd5c Horario: 09:00 a 16:00 horas \ud83d\udd4a\ufe0f La Jornada de Paz es una iniciativa impulsada por la Presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, que acerca servicios, orientaci\u00f3n y atenci\u00f3n directa a la poblaci\u00f3n mediante &hellip; <\/p>\n","protected":false},"author":1,"featured_media":112412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,14,28,29,7,11,15,16,4],"tags":[],"class_list":["post-112410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-caneros","category-cnc","category-cnpr","category-ciudad","category-estado","category-ganaderos","category-ingenios","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/112410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=112410"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/112410\/revisions"}],"predecessor-version":[{"id":112413,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/112410\/revisions\/112413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/112412"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=112410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=112410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=112410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}