{"id":113661,"date":"2026-05-13T08:06:33","date_gmt":"2026-05-13T14:06:33","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=113661"},"modified":"2026-05-13T08:06:35","modified_gmt":"2026-05-13T14:06:35","slug":"gobierno-municipal-de-tamasopo-y-snte-seccion-26-unen-esfuerzos-para-una-nueva-clinica-del-issste","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/gobierno-municipal-de-tamasopo-y-snte-seccion-26-unen-esfuerzos-para-una-nueva-clinica-del-issste\/","title":{"rendered":"Gobierno Municipal de Tamasopo y SNTE Secci\u00f3n 26 unen esfuerzos para una nueva cl\u00ednica del ISSSTE"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>El Cabildo de la administraci\u00f3n 2024-2027 encabezada por el presidente municipal Mauricio Andrade, en coordinaci\u00f3n con el SNTE Secci\u00f3n 26 ha concretado un importante acuerdo para la donaci\u00f3n de un terreno donde ser\u00e1 instalada una moderna cl\u00ednica del ISSSTE.<\/p>\n\n\n\n<p>Este importante avance es resultado del trabajo en conjunto y del compromiso por seguir sumando m\u00e1s beneficios para las familias de Tamasopo<\/p>\n\n\n\n<p>La construcci\u00f3n de esta cl\u00ednica beneficiar\u00e1 a todos los habitantes del municipio, fortaleciendo los servicios de salud y acercando una mejor atenci\u00f3n m\u00e9dica para todos.<\/p>\n\n\n\n<p>\u00a1Seguimos construyendo un mejor Tamasopo para todos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cabildo de la administraci\u00f3n 2024-2027 encabezada por el presidente municipal Mauricio Andrade, en coordinaci\u00f3n con el SNTE Secci\u00f3n 26 ha concretado un importante acuerdo para la donaci\u00f3n de un terreno donde ser\u00e1 instalada una moderna cl\u00ednica del ISSSTE. Este importante avance es resultado del &hellip; <\/p>\n","protected":false},"author":1,"featured_media":113662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,14,28,29,11,15,4,10,12,31,21],"tags":[],"class_list":["post-113661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-caneros","category-cnc","category-cnpr","category-estado","category-ganaderos","category-inicio","category-municipios","category-nacional","category-sanluispotosi","category-tamasopo"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/113661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=113661"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/113661\/revisions"}],"predecessor-version":[{"id":113663,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/113661\/revisions\/113663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/113662"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=113661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=113661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=113661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}