{"id":115022,"date":"2026-07-15T08:40:33","date_gmt":"2026-07-15T14:40:33","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=115022"},"modified":"2026-07-15T08:40:35","modified_gmt":"2026-07-15T14:40:35","slug":"el-gobernador-ricardo-gallardo-anuncia-nuevo-distribuidor-vial-en-zona-poniente","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/el-gobernador-ricardo-gallardo-anuncia-nuevo-distribuidor-vial-en-zona-poniente\/","title":{"rendered":"El gobernador Ricardo Gallardo anuncia nuevo distribuidor vial en zona poniente"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Con una inversi\u00f3n de mil 400 millones de pesos, la obra tendr\u00e1 dos kil\u00f3metros y conectar\u00e1 Sierra Leona, Villa Magna, Camino a la Presa y R\u00edo Santiago.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, anunci\u00f3 la construcci\u00f3n de un nuevo distribuidor vial de dos kil\u00f3metros en la zona poniente de la capital, que contar\u00e1 con una inversi\u00f3n de mil 400 millones de pesos y permitir\u00e1 mejorar la conexi\u00f3n entre avenida Sierra Leona, Villa Magna, Camino a la Presa, R\u00edo Santiago y otras vialidades de alta afluencia vehicular.<\/p>\n\n\n\n<p>El Mandatario Estatal explic\u00f3 que el proyecto incluir\u00e1 diversos ramales de incorporaci\u00f3n y salida, con un dise\u00f1o similar al Distribuidor Ju\u00e1rez, para facilitar los desplazamientos entre distintos sectores de la ciudad, reducir los tiempos de traslado y brindar mayor seguridad a miles de automovilistas.<\/p>\n\n\n\n<p>Detall\u00f3 que la obra forma parte del programa de modernizaci\u00f3n de la infraestructura vial que desarrolla el Gobierno del Estado para atender el crecimiento urbano de la zona metropolitana y responder a la demanda de una movilidad m\u00e1s ordenada, eficiente y segura.<\/p>\n\n\n\n<p>Ricardo Gallardo adelant\u00f3 que los trabajos est\u00e1n previstos para iniciar entre diciembre de 2026 y enero de 2027, una vez concluida la construcci\u00f3n del Puente de la Familia, lo que permitir\u00e1 mantener la continuidad de las grandes obras de movilidad en la capital potosina.<\/p>\n\n\n\n<p>El Gobernador destac\u00f3 que este nuevo distribuidor transformar\u00e1 la conectividad del poniente de la ciudad y dar\u00e1 respuesta a uno de los corredores con mayor crecimiento habitacional y vehicular de San Luis Potos\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, anunci\u00f3 la construcci\u00f3n de un nuevo distribuidor vial de dos kil\u00f3metros en la zona poniente de la capital, que contar\u00e1 con una inversi\u00f3n de mil 400 millones de pesos y permitir\u00e1 mejorar la conexi\u00f3n entre avenida &hellip; <\/p>\n","protected":false},"author":1,"featured_media":115023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,14,7,4,30,31,59,21],"tags":[],"class_list":["post-115022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agropecuaria","category-caneros","category-ciudad","category-inicio","category-rioverde","category-sanluispotosi","category-santa-catarina","category-tamasopo"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/115022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=115022"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/115022\/revisions"}],"predecessor-version":[{"id":115024,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/115022\/revisions\/115024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/115023"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=115022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=115022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=115022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}