{"id":12196,"date":"2016-05-13T21:47:28","date_gmt":"2016-05-14T03:47:28","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2016\/05\/13\/festejan-a-mamas-de-los-talleres-de-casa-de-la-cultura\/"},"modified":"2016-05-13T21:47:28","modified_gmt":"2016-05-14T03:47:28","slug":"festejan-a-mamas-de-los-talleres-de-casa-de-la-cultura","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/festejan-a-mamas-de-los-talleres-de-casa-de-la-cultura\/","title":{"rendered":"FESTEJAN A MAMAS DE LOS TALLERES DE CASA DE LA CULTURA"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"caption\"><br \/>Tamuin.- Dentro de los festejos del d\u00eda de las madres en esta ocasi\u00f3n las mam\u00e1s del taller de bordado T\u00e9nek de la Casa de la Cultura\u00a0 recibieron su festejo el cual fue organizado por la direcci\u00f3n de la casa de la casa de la cultura que encabeza\u00a0 Yuridia Hernandez P\u00e9rez y\u00a0 Laura Patricia Reyes Plascencia as\u00ed como tambi\u00e9n por la Regidora comisionada de esta \u00e1rea la\u00a0 Anaid Herbert Ru\u00edz.<br \/>Dentro del convivio las alumnas de la profesora Ana Leticia Kullick Rodriguez responsable de esta actividad mostraron para difundir en los medios de comunicaci\u00f3n los trabajos que se elaboran dentro de este taller en manteles, blusas y bolsos.<br \/>As\u00ed mismo se invit\u00f3 a las personas\u00a0 interesadas en realizar esta actividad todos los martes de 3 a 6 de la tarde en la Casa de la Cultura.<\/span><br \/>&#8212;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tamuin.- Dentro de los festejos del d\u00eda de las madres en esta ocasi\u00f3n las mam\u00e1s del taller de bordado T\u00e9nek de la Casa de la Cultura\u00a0 recibieron su festejo el cual fue organizado por la direcci\u00f3n de la casa de la casa de la cultura &hellip; <\/p>\n","protected":false},"author":1,"featured_media":12195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-12196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tamuin"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/12196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=12196"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/12196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/12195"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=12196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=12196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=12196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}