{"id":12418,"date":"2016-06-01T13:17:31","date_gmt":"2016-06-01T19:17:31","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2016\/06\/01\/se-realizan-segunda-sesian-del-consejo-de-salud-en-tamuin\/"},"modified":"2016-06-01T13:17:31","modified_gmt":"2016-06-01T19:17:31","slug":"se-realizan-segunda-sesian-del-consejo-de-salud-en-tamuin","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/se-realizan-segunda-sesian-del-consejo-de-salud-en-tamuin\/","title":{"rendered":"SE REALIZAN SEGUNDA SESI\u00d3N DEL CONSEJO DE SALUD EN TAMUIN"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"caption\">Tamuin.-\u00a0 El d\u00eda de hoy se realiz\u00f3 en la sala de cabildo del Ayuntamiento de Tamu\u00edn la Segunda Sesi\u00f3n Ordinaria del Concejo Municipal de Salud con una conferencia magistral sobre el Dengue, Zika y Chikungunya impartida por el Coordinador Municipal de Salud Dr. Jos\u00e9 Luis Medina Gudi\u00f1o.<br \/>Al t\u00e9rmino de la pl\u00e1tica se realiz\u00f3 una sesi\u00f3n de preguntas y respuestas y para finalizar se hizo una presentaci\u00f3n de todas las actividades realizadas por la coordinaci\u00f3n de salud.<br \/>Entre las personalidades destacadas que acudieron al evento se encontraban: el Presidente Municipal, directores y jefe de departamento, Luz Mar\u00eda L\u00f3pez Tinajero Directora del SMDIF Tamu\u00edn en representaci\u00f3n de Sandra Tinajero Zamudio Presidenta del SMDif Tamu\u00edn.<br \/> Francisco Adri\u00e1n Castillo Morales, Asesor T\u00e9cnico, Cristian Austria Balderas, Jefe del Departamento de Epidemiolog\u00eda, Salvador de Jes\u00fas Orta Villegas, Director del Hospital B\u00e1sico Comunitario, Fabiola Alonso S\u00e1nchez, Encargada del Centro de Salud.<br \/>As\u00ed mismo, Josefina Lara Barr\u00f3n, Administradora del Hospital B\u00e1sico Comunitario, Catalina Del \u00c1ngel Cervantes, Directora del Seguro Social, Carlos Delgado Arnaud, Responsable de Promoci\u00f3n a la Salud, Esther Alejandra Flores, Encargada de la coordinaci\u00f3n de prevenci\u00f3n y promoci\u00f3n para la salud y Roberto Purata Gonz\u00e1lez, Coordinador de la COEPRIS.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tamuin.-\u00a0 El d\u00eda de hoy se realiz\u00f3 en la sala de cabildo del Ayuntamiento de Tamu\u00edn la Segunda Sesi\u00f3n Ordinaria del Concejo Municipal de Salud con una conferencia magistral sobre el Dengue, Zika y Chikungunya impartida por el Coordinador Municipal de Salud Dr. Jos\u00e9 Luis &hellip; <\/p>\n","protected":false},"author":1,"featured_media":12417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-12418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tamuin"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/12418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=12418"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/12418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/12417"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=12418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=12418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=12418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}