{"id":17081,"date":"2017-08-10T23:08:01","date_gmt":"2017-08-11T05:08:01","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2017\/08\/10\/cemex-da-a-conocer-finalistas-de-premio-obras-2017\/"},"modified":"2017-08-10T23:08:01","modified_gmt":"2017-08-11T05:08:01","slug":"cemex-da-a-conocer-finalistas-de-premio-obras-2017","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/cemex-da-a-conocer-finalistas-de-premio-obras-2017\/","title":{"rendered":"CEMEX da a conocer finalistas de premio obras 2017"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"caption\"><br \/><span class=\"caption\"><br \/>\u2022\u00a0\u00a0\u00a0 Selecciona ganadora de Beca Arq. Marcelo Zambrano<\/p>\n<p>MONTERREY, N.L. 10 DE AGOSTO DE 2017.- CEMEX, S.A.B. de C.V. (\u00abCEMEX\u00bb) (BMV: CEMEXCPO) anunci\u00f3 hoy a los finalistas de la edici\u00f3n 26 del Premio Obras CEMEX, as\u00ed como a la ganadora de la Beca Arq. Marcelo Zambrano 2017.<br \/>Entre las 16 obras seleccionadas se encuentran: la Casa del Abuelo en Chiapas, el Centro Cultural Comunitario Teotitl\u00e1n del Valle, la Ciudad de los Archivos, el Edificio del Archivo Hist\u00f3rico del Estado en Oaxaca, as\u00ed como la Torre Reforma en la Ciudad de M\u00e9xico. Las obras finalistas de la Edici\u00f3n M\u00e9xico del Premio Obras CEMEX 2017 las puede consultar en nuestra p\u00e1gina de internet: http:\/\/www.cemexmexico.com\/premioobra\/FinalistasNacionales2017.aspx<br \/>\u201cCon el Premio Obras CEMEX tenemos la oportunidad de reconocer a las obras que promueven mejores pr\u00e1cticas constructivas mientras que, con la Beca Arq. Marcelo Zambrano, apoyamos a los j\u00f3venes talentos que quieren contribuir a la construcci\u00f3n y el dise\u00f1o en nuestro pa\u00eds. Ambos cert\u00e1menes tienen como objetivo destacar lo mejor de la construcci\u00f3n a nivel nacional y mundial\u201d afirm\u00f3 Juan Romero, presidente de CEMEX M\u00e9xico.<br \/>En esta edici\u00f3n del Premio Obras CEMEX, 545 obras mexicanas fueron evaluadas por un jurado integrado por 13 personalidades de la industria de la construcci\u00f3n provenientes de Colombia, Estados Unidos, Francia, M\u00e9xico, Panam\u00e1, Puerto Rico y Rep\u00fablica Dominicana.<br \/>Durante la deliberaci\u00f3n, realizada del 14 al 16 de junio en el Museo Internacional del Barroco de Puebla, obra merecedora de varios reconocimientos en la Edici\u00f3n 2016, el jurado eligi\u00f3 16 obras como finalistas en las cinco categor\u00edas, y seleccion\u00f3 las obras ganadoras de los Premios Especiales, adem\u00e1s de otorgar dos Menciones Honor\u00edficas en estos \u00faltimos. <br \/>Los ganadores se dar\u00e1n a conocer durante la ceremonia de premiaci\u00f3n que se llevar\u00e1 a cabo el pr\u00f3ximo 9 de noviembre en la Ciudad de M\u00e9xico. <\/p>\n<p>Adem\u00e1s, el pasado 13 de julio un consejo de reconocidos arquitectos mexicanos eligi\u00f3 a la Arq. Karla Paola L\u00f3pez Carrillo como ganadora de la Beca Arq. Marcelo Zambrano 2017.<\/p>\n<p>De entre las aplicaciones recibidas de 43 j\u00f3venes arquitectos mexicanos, la egresada del Instituto Tecnol\u00f3gico de Tepic destac\u00f3 por su trabajo acad\u00e9mico y profesional, por lo que recibir\u00e1 un apoyo econ\u00f3mico integral para cursar la Maestr\u00eda de Arquitectura del Paisaje en la Universidad Polit\u00e9cnica de Catalunya, en Barcelona, Espa\u00f1a. Para conocer m\u00e1s detalle de esta beca puede consultar la p\u00e1gina de internet: http:\/\/www.cemexmexico.com\/premioobra\/BecaMarceloZambrano.aspx<br \/>Mediante cert\u00e1menes como el Premio Obras CEMEX, que cumple 26 a\u00f1os de trascender fronteras, y la Beca Arq. Marcelo Zambrano, CEMEX reconoce el esfuerzo de quienes, a trav\u00e9s de proyectos arquitect\u00f3nicos y constructivos innovadores, contribuyen a construir un mejor futuro.<\/span><\/span><span class=\"caption\"><br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022\u00a0\u00a0\u00a0 Selecciona ganadora de Beca Arq. Marcelo Zambrano MONTERREY, N.L. 10 DE AGOSTO DE 2017.- CEMEX, S.A.B. de C.V. (\u00abCEMEX\u00bb) (BMV: CEMEXCPO) anunci\u00f3 hoy a los finalistas de la edici\u00f3n 26 del Premio Obras CEMEX, as\u00ed como a la ganadora de la Beca Arq. Marcelo &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-17081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=17081"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17081\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17080"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=17081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=17081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=17081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}