{"id":17233,"date":"2017-08-25T02:29:25","date_gmt":"2017-08-25T08:29:25","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2017\/08\/25\/denuncia-diputado-federal-al-alcalde-de-tanlajas-por-difamacia%c2%b3n\/"},"modified":"2017-08-25T02:29:25","modified_gmt":"2017-08-25T08:29:25","slug":"denuncia-diputado-federal-al-alcalde-de-tanlajas-por-difamacia%c2%b3n","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/denuncia-diputado-federal-al-alcalde-de-tanlajas-por-difamacia%c2%b3n\/","title":{"rendered":"Denuncia Diputado Federal al alcalde de Tanlajas por difamaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span class=\"caption\">Se\u00f1alamientos en m<\/span><span style=\"font-size: 12.16px;\">i contra son una total mentira: CJS<\/span><\/p>\n<p class=\"caption\" style=\"text-align: justify;\">Xilitla.- En entrevista el diputado federal Cristian Joaqu\u00edn S\u00e1nchez, dijo que desde \u00a0un se pronuncio contra de que talen nuestros \u00e1rboles y afecte a nuestro medio ambiente antes de que se hicieran esos se\u00f1alamientos sostuve una reuni\u00f3n con el alcalde donde en conjunto plante\u00e1bamos defender el bosque de Xilitla y el alcalde es otra fuerza pol\u00edtica y puede corroborar la postura de su diputado.<\/p>\n<p class=\"caption\" style=\"text-align: justify;\">Expres\u00f3 que pueden investigar qu\u00e9 no hay ninguna empresa en Singapur no tengo ninguna intervenci\u00f3n del Diputado Federal para talar \u00e1rboles.<\/p>\n<p class=\"caption\" style=\"text-align: justify;\">Destac\u00f3 que la intervenci\u00f3n es en contra de que est\u00e9n tumbando nuestros \u00e1rboles.<\/p>\n<p class=\"caption\" style=\"text-align: justify;\">Por otra parte dijo que hoy mismo presentar\u00e1 una denuncia ante Comisi\u00f3n de Derechos Humanos en contra de quienes siendo autoridades se atrevieron a presentar su opini\u00f3n con descalificaciones sin sustento y contra el peri\u00f3dico que sin confirmar la fuente real estuvo tratando de da\u00f1ar mi imagen.<\/p>\n<p class=\"caption\" style=\"text-align: justify;\">Por lo que aseguro, presentara una\u00a0 denuncia contra peri\u00f3dico el Arco Moctezuma, y contra Domingo Rodr\u00edguez Martell por difamaci\u00f3n y los que resulte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Se\u00f1alamientos en mi contra son una total mentira: CJS Xilitla.- En entrevista el diputado federal Cristian Joaqu\u00edn S\u00e1nchez, dijo que desde \u00a0un se pronuncio contra de que talen nuestros \u00e1rboles y afecte a nuestro medio ambiente antes de que se hicieran esos se\u00f1alamientos sostuve &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=17233"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=17233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=17233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=17233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}