{"id":17259,"date":"2017-08-28T14:17:01","date_gmt":"2017-08-28T20:17:01","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2017\/08\/28\/acuerdan-jm-carreras-y-josa-narro-renovacia%c2%b3n-integral-del-hospital-central\/"},"modified":"2017-08-28T14:17:01","modified_gmt":"2017-08-28T20:17:01","slug":"acuerdan-jm-carreras-y-josa-narro-renovacia%c2%b3n-integral-del-hospital-central","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/acuerdan-jm-carreras-y-josa-narro-renovacia%c2%b3n-integral-del-hospital-central\/","title":{"rendered":"Acuerdan JM Carreras y Jos\u00e9 Narro renovaci\u00f3n integral del hospital central"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"caption\"><br \/>* Tambi\u00e9n se ampliar\u00e1 el Hospital del Ni\u00f1o y la Mujer.<br \/>* M\u00e1s de mil millones de pesos se invertir\u00e1n en ambas obras.<br \/>* Agradeci\u00f3 el apoyo del Presidente de la Rep\u00fablica, Enrique Pe\u00f1a Nieto.<br \/>Ciudad de M\u00e9xico.- Con una inversi\u00f3n superior a los mil millones de pesos se llevar\u00e1 a cabo la renovaci\u00f3n integral del Hospital Central \u201cDr. Ignacio Morones Prieto\u201d y de la ampliaci\u00f3n del Hospital de El Ni\u00f1o y la Mujer, confirm\u00f3 el Gobernador del Estado Juan Manuel Carreras L\u00f3pez, luego de sostener una reuni\u00f3n en la Ciudad de M\u00e9xico con el secretario de Salud del Gobierno Federal Jos\u00e9 Narro Robles.<br \/>Carreras L\u00f3pez dijo que tras d\u00e9cadas de brindar un gran servicio a las y los potosinos, as\u00ed como a habitantes de otros estados, el Hospital Central ser\u00e1 pr\u00e1cticamente reconstruido en la misma ubicaci\u00f3n actual, y tambi\u00e9n equipado, gracias al apoyo del Presidente de la Rep\u00fablica, Enrique Pe\u00f1a Nieto, para mejorar las condiciones de infraestructura hospitalaria en beneficio de las y los potosinos.<br \/>En el encuentro, donde se analizaron los pormenores de la obra, tambi\u00e9n se dio a conocer el pr\u00f3ximo inicio de la ampliaci\u00f3n y mejoramiento del hospital del Ni\u00f1o y la Mujer \u201cDr. Alberto L\u00f3pez Hermosa\u201d.<br \/>Narro Robles explic\u00f3 que durante el Gobierno del Presidente Enrique Pe\u00f1a Nieto, se han hecho un gran n\u00famero de obras y mejora de la infraestructura de salud en San Luis Potos\u00ed por un monto de inversi\u00f3n cercano a los 1 mil 300 millones de pesos, de las cuales 38 ya han sido concluidas, 5 se encuentran en proceso y se tienen proyectadas dos m\u00e1s (los hospitales Central y del Ni\u00f1o y la Mujer).<br \/>Detall\u00f3 que la renovaci\u00f3n del Hospital Central, incluir\u00e1 80 consultorios, 250 camas, 13 salas quir\u00fargicas, dos salas de expulsi\u00f3n en una superficie de terreno de m\u00e1s de 30 mil metros cuadrados.<br \/>Carreras L\u00f3pez se\u00f1al\u00f3 que el renovado Hospital Central, es resultado de las gestiones de la administraci\u00f3n estatal ante el Gobierno Federal, \u201cpor la edad de la construcci\u00f3n del actual hospital, se decidi\u00f3 que era momento de renovarlo, sustituirlo porque el servicio que se presta as\u00ed lo obliga, y ya no se pod\u00eda seguir remendando, era necesario un nuevo edificio y se logr\u00f3\u201d.<br \/>A la par, el Ejecutivo estatal y el Secretario de Salud Federal dialogaron sobre el arranque\u00a0 de los trabajos de ampliaci\u00f3n de las instalaciones del Hospital del Ni\u00f1o y la Mujer \u201cDr. Alberto L\u00f3pez Hermosa\u201d, para lo cual ya est\u00e1n etiquetados cerca 50 millones de pesos.<br \/>A su vez, el mandatario estatal Carreras L\u00f3pez indic\u00f3 que gracias al apoyo del Presidente Enrique Pe\u00f1a Nieto y del secretario de Salud, Jos\u00e9 Narro Robles, el Hospital del Ni\u00f1o y la Mujer contar\u00e1 con\u00a030 camas adicionales. \u201cLas obras quedar\u00e1n concluidas en el a\u00f1o 2018, con lo que ofrecer\u00e1 mayor y mejor atenci\u00f3n a las ni\u00f1as, ni\u00f1os y madres\u201d, puntualiz\u00f3.<br \/>Carreras L\u00f3pez sostuvo que el proyecto parte de las gestiones efectuadas ante el Gobierno Federal que han sido concretadas y se encuentran en proceso para su pr\u00f3xima ejecuci\u00f3n.<br \/>Finalmente, el mandatario potosino extern\u00f3 su reconocimiento al funcionario federal por encontrar las f\u00f3rmulas para mantener los esfuerzos de las instituciones p\u00fablicas de salud, para llevar a cabo las obras de infraestructura hospitalaria en San Luis Potos\u00ed, a favor de las y los habitantes potosinos. <br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>* Tambi\u00e9n se ampliar\u00e1 el Hospital del Ni\u00f1o y la Mujer.* M\u00e1s de mil millones de pesos se invertir\u00e1n en ambas obras.* Agradeci\u00f3 el apoyo del Presidente de la Rep\u00fablica, Enrique Pe\u00f1a Nieto.Ciudad de M\u00e9xico.- Con una inversi\u00f3n superior a los mil millones de pesos &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=17259"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17258"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=17259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=17259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=17259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}