{"id":17264,"date":"2017-08-28T20:49:36","date_gmt":"2017-08-29T02:49:36","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2017\/08\/28\/brindan-estatales-ayuda-en-el-hospital-regional-de-rioverde-ante-inundaciones\/"},"modified":"2017-08-28T20:49:36","modified_gmt":"2017-08-29T02:49:36","slug":"brindan-estatales-ayuda-en-el-hospital-regional-de-rioverde-ante-inundaciones","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/brindan-estatales-ayuda-en-el-hospital-regional-de-rioverde-ante-inundaciones\/","title":{"rendered":"Brindan estatales ayuda en el hospital regional de Rioverde ante inundaciones"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"caption\"><br \/>Rioverde S.L.P.- Dentro de los trabajos que realizan Polic\u00edas de la Secretar\u00eda de Seguridad P\u00fablica del Estado para salvaguardar la integridad y patrimonio de la poblaci\u00f3n, ayer brindaron ayuda y salvaguarda en las instalaciones del Hospital Regional de Rioverde, luego de que este resultara afectado por torrenciales lluvias.<br \/>Debido a las lluvias registradas, el \u00e1rea de urgencias m\u00e9dicas del nosocomio comenz\u00f3 a inundarse, afectando el agua no solamente a familiares y personal, sino que compromet\u00eda el bienestar de pacientes y equipo m\u00e9dico, por lo que de inmediato, personal de la SSPE inici\u00f3 labores de ayuda sacando el agua del lugar para evitar situaciones que arriesgaran a las personas ah\u00ed presentes.<br \/>Con herramienta de limpieza, el apoyo se extendi\u00f3 de la noche a la madrugada, hasta que la situaci\u00f3n estuvo controlada. Sin embargo, personal de la SSPE se mantiene alerta para evitar contingencias debido a que el pron\u00f3stico del clima prev\u00e9 m\u00e1s precipitaciones pluviales que podr\u00edan afectar el funcionamiento del nosocomio y otros edificios p\u00fablicos.<br \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rioverde S.L.P.- Dentro de los trabajos que realizan Polic\u00edas de la Secretar\u00eda de Seguridad P\u00fablica del Estado para salvaguardar la integridad y patrimonio de la poblaci\u00f3n, ayer brindaron ayuda y salvaguarda en las instalaciones del Hospital Regional de Rioverde, luego de que este resultara afectado &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=17264"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17263"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=17264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=17264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=17264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}