{"id":17353,"date":"2017-09-06T23:51:35","date_gmt":"2017-09-07T05:51:35","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2017\/09\/06\/tres-sistemas-meteorola%c2%b3gicos-ocasionan-lluvias-en-slp\/"},"modified":"2017-09-06T23:51:35","modified_gmt":"2017-09-07T05:51:35","slug":"tres-sistemas-meteorola%c2%b3gicos-ocasionan-lluvias-en-slp","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/tres-sistemas-meteorola%c2%b3gicos-ocasionan-lluvias-en-slp\/","title":{"rendered":"Tres sistemas meteorol\u00f3gicos ocasionan lluvias en SLP"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"caption\"><\/p>\n<p>San Luis Potos\u00ed.- Lluvias de ligeras a moderadas se registraron en las 4 zonas del estado sin ocasionar hasta el momento afectaciones de consideraci\u00f3n, dio a conocer la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil quien detall\u00f3 que las lluvias est\u00e1n siendo ocasionadas por un canal de baja presi\u00f3n ubicado en el occidente de M\u00e9xico y por la interacci\u00f3n del Frente Fr\u00edo N\u00famero 2, que se extender\u00e1 en el norte y el noreste del pa\u00eds, con la tormenta tropical Katia, desarrollada en el Golfo de M\u00e9xico, a partir de la Depresi\u00f3n Tropical 13.<br \/>De acuerdo a informaci\u00f3n del Servicio Meteorol\u00f3gico Nacional a las 07:00 horas, tiempo del centro de M\u00e9xico, Katia se localiz\u00f3 aproximadamente a 175 kil\u00f3metros (km) al este de Tampico, Tamaulipas, y a 125 km al este-noreste de Cabo Rojo, Veracruz, con vientos m\u00e1ximos sostenidos de 65 km\/h, rachas de 85 km\/h y desplazamiento al este-sureste a 4 km\/h.<br \/>La dependencia estatal advirti\u00f3 sobre diversos fen\u00f3menos que podr\u00edan presentarse a partir de estas precipitaciones y recomend\u00f3 extremar precauciones ante las probabilidades de lluvias puntuales intensas, as\u00ed como mantenerse al tanto de la informaci\u00f3n que se emita por los medios de comunicaci\u00f3n y redes sociales oficiales.<br \/>Adelant\u00f3 que podr\u00edan continuar e incrementarse las restricciones en los parajes con actividad acu\u00e1tica, pidi\u00f3 extremar precauciones ante posibles deslaves o derrumbes en zonas serranas o si hay agrietamientos, escarpes o rodamiento de piedras en laderas o cerros, pueden implicar riesgo de deslaves. <br \/>Solicit\u00f3 a la ciudadan\u00eda que antes de salir a carretera verifique el funcionamiento electromec\u00e1nico y limpiaparabrisas, extreme precauciones al transitar por carreteras, brechas y caminos rurales ante baja visibilidad, terreno resbaladizo, posibles deslaves de sierras o avenidas s\u00fabitas de agua con material de arrastre y estar atenta ante inundaciones y crecientes en r\u00edos de respuesta r\u00e1pida. <br \/>Recomend\u00f3 no intentar cruzar cauces de r\u00edos, arroyos, vados y zonas bajas, por posible arrastre por el agua, ante cualquier indicativo de inundaci\u00f3n o deslave evacuar de inmediato la zona y si las autoridades les piden desalojar su vivienda, hacerlo de manera inmediata.<br \/>Finalmente record\u00f3 las redes oficiales de la dependencia, en Twitter @PC_SLP, en Facebook como Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil SLP y el n\u00famero de emergencia 9-1-1.<\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Luis Potos\u00ed.- Lluvias de ligeras a moderadas se registraron en las 4 zonas del estado sin ocasionar hasta el momento afectaciones de consideraci\u00f3n, dio a conocer la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil quien detall\u00f3 que las lluvias est\u00e1n siendo ocasionadas por un canal de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=17353"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=17353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=17353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=17353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}