{"id":17354,"date":"2017-09-06T23:52:16","date_gmt":"2017-09-07T05:52:16","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2017\/09\/06\/sspe-recupera-24-veha%c2%adculos-y-detiene-a-19-presuntos-por-diversos-delitos-en-una-semana\/"},"modified":"2017-09-06T23:52:16","modified_gmt":"2017-09-07T05:52:16","slug":"sspe-recupera-24-veha%c2%adculos-y-detiene-a-19-presuntos-por-diversos-delitos-en-una-semana","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/sspe-recupera-24-veha%c2%adculos-y-detiene-a-19-presuntos-por-diversos-delitos-en-una-semana\/","title":{"rendered":"SSPE recupera 24 veh\u00edculos y detiene a 19 presuntos por diversos delitos en una semana"},"content":{"rendered":"<p style=\"text-align: justify;\"><span class=\"caption\"><\/p>\n<p>San Luis Potos\u00ed.- Como parte del trabajo de coordinaci\u00f3n que mantiene la Secretar\u00eda de Seguridad P\u00fablica del Estado (SSPE) con Polic\u00edas Municipales, Federales y elementos de la Secretar\u00eda de la Defensa Nacional, del 26 de agosto al 1 de septiembre, se lograron recuperar 24 veh\u00edculos con reporte de robo, el aseguramiento de 45 dosis de marihuana y 41 dosis de cristal as\u00ed como el decomiso de dos armas de fuego.<br \/>En diferentes acciones se llevaron a cabo 19 detenciones relevantes de presuntos por delitos de robo con violencia, por conducir veh\u00edculo con reporte de robo, por robo a negocio, por posesi\u00f3n de arma prohibida y por contar con orden de aprehensi\u00f3n as\u00ed como por delitos contra la salud.<br \/>Tambi\u00e9n como parte del trabajo de coordinaci\u00f3n de acciones seguridad entre la Polic\u00eda Estatal y Municipal, en la Zona Metropolitana, se recorrieron y patrullaron mil 834 colonias, barrios y fraccionamientos de la Zona Metropolitana, as\u00ed como la inspecci\u00f3n de 587 personas, lo que llev\u00f3 a la puesta a disposici\u00f3n del Ministerio P\u00fablico del Fuero Com\u00fan de 39 y dos m\u00e1s ante el Ministerio P\u00fablico del Fuero Federal, 530 personas fueron canalizados ante un Juez Calificador y 30 menores de edad a trabajo social, por diferentes faltas.<br \/>En la semana del 26 de agosto al 1 de septiembre, las corporaciones de seguridad brindaron atenci\u00f3n en 64 accidentes viales y realizaron 152 servicios sociales en los diferentes sectores geogr\u00e1ficos de la Zona Metropolitana.<br \/>Adem\u00e1s, con la finalidad de disminuir el \u00edndice delictivo se desplegaron diversas c\u00e9lulas de reacci\u00f3n conjuntas entre la Polic\u00eda Estatal y las Polic\u00edas Municipales de San Luis Potos\u00ed y Soledad de Graciano S\u00e1nchez, a fin de patullar y vigilar m\u00e1s de 41 colonias y barrios, entre las cuales se citan\u00a0Cactus, La Virgen, Pav\u00f3n, Villa Alborada, Primera de Mayo, 21 de Marzo, Hogares Ferrocarrileros, Praderas del Maurel, El Morro, San Antonio, San Francisco, Soledad Centro, Las Flores, La Lomita y Hogares Populares Pav\u00f3n.<br \/>Tambi\u00e9n se patrullaron a lo largo de la semana las colonias Progreso, Santa Fe, Juli\u00e1n Carrillo, Sim\u00f3n D\u00edaz, General I. Mart\u00ednez, Los Silos, Prados 1, 2 y 3, Ciudad 2000, Zona Centro de la Capital Potosina, Ferrocarrilera, San Felipe, Las Piedras, Las Flores, Ponciano Arriaga, Mezquital, Los Limones, Valle Escondido, Condominios San Miguel, Los Pinos, Los Magueyes y Las Terceras.<br \/>Por otro lado, y dentro\u00a0de los recorridos de seguridad y vigilancia que realiza la Polic\u00eda Estatal, sobre la carretera Estatal Rioverde-Cerritos, delegaci\u00f3n Pastora, en el municipio de Rioverde, dentro del Operativo \u201c\u00c9bano Seguro\u201d,\u00a0se detuvo dos personas, por el presunto delito de posesi\u00f3n il\u00edcita de mil 400 litros de gasolina y aseguraron dos veh\u00edculos.<br \/>Como parte de las acciones de proximidad social y atenci\u00f3n a la ciudadan\u00eda, Polic\u00edas Estatales en el municipio de Rioverde, evitaron que una mujer fuera v\u00edctima de presunto delito de extorsi\u00f3n telef\u00f3nica e impidieron que depositar\u00e1 30 mil pesos a presuntos delincuentes.<br \/>En otra acci\u00f3n, Polic\u00edas Estatales en el municipio de Axtla de Terrazas, en la regi\u00f3n huasteca, recataron a un hombre que estaba presuntamente privado de la libertad y se detuvo un presunto.<br \/>Las corporaciones de los tres niveles de gobierno en materia de seguridad p\u00fablica en la Zona Metropolitana, atendieron un total de 2,609 auxilios reales reportados al Sistema de Emergencia 9-1-1.<br \/>Durante la \u00faltima semana del mes de agosto y principios de la semana de septiembre se instalaron tres Operativos extraordinarios, \u201c15 pagos del Programa 65 y m\u00e1s, \u201cSesi\u00f3n del Congreso\u201d y \u201cRebote\u201d, los cuales buscan inhibir conductas antisociales que pongan en peligro la tranquilidad de la sociedad.<br \/>&#8212;<\/span><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Luis Potos\u00ed.- Como parte del trabajo de coordinaci\u00f3n que mantiene la Secretar\u00eda de Seguridad P\u00fablica del Estado (SSPE) con Polic\u00edas Municipales, Federales y elementos de la Secretar\u00eda de la Defensa Nacional, del 26 de agosto al 1 de septiembre, se lograron recuperar 24 veh\u00edculos &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=17354"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/17354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=17354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=17354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=17354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}