{"id":21751,"date":"2018-02-25T13:32:46","date_gmt":"2018-02-25T19:32:46","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=21751"},"modified":"2018-02-25T13:32:46","modified_gmt":"2018-02-25T19:32:46","slug":"traves-de-diversos-operativos-logra-sspe-recuperar-37-unidades-con-reporte-de-robo-en-una-semana","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/traves-de-diversos-operativos-logra-sspe-recuperar-37-unidades-con-reporte-de-robo-en-una-semana\/","title":{"rendered":"A trav\u00e9s de diversos operativos logra SSPE recuperar 37 unidades con reporte de robo en una semana"},"content":{"rendered":"<p>San Luis Potos\u00ed.- A trav\u00e9s de los operativos \u201cTrueno\u201d, \u201cProtector\u201d, \u201cAntialcohol\u201d y patrullaje terrestre y a\u00e9reo articulados por la Secretar\u00eda de Seguridad P\u00fablica del Gobierno del Estado (SSPE) as\u00ed como vigilancia en tiendas de conveniencia, en el Centro Hist\u00f3rico capitalino y de Abastos y en gasolineras, dio como resultado la recuperaci\u00f3n de 31 automotores robados y 6 motocicletas.<\/p>\n<p>La dependencia dio a conocer que se instalaron filtros m\u00f3viles para la detecci\u00f3n y aseguramiento de criminales y armas de fuego.<\/p>\n<p>Adem\u00e1s inform\u00f3 que Se contin\u00faa con el protocolo de atenci\u00f3n y seguimiento en Coordinaci\u00f3n con la Comisi\u00f3n Ejecutiva Estatal de Atenci\u00f3n a V\u00edctimas con 61 casos atendidos, as\u00ed como 162 medidas de prevenci\u00f3n o alertas dirigidas a trav\u00e9s del twitter @Ciber_ssp_slp y 9 asesor\u00edas otorgadas a trav\u00e9s de la Polic\u00eda Cibern\u00e9tica. <\/p>\n<p>En la semana del 10 al 16 de febrero la SSPE logr\u00f3 decomisar 422 gramos de marihuana, 71 dosis de cristal, 6 dosis de coca\u00edna, 4 celulares, 5 armas cortas, 2 armas largas 64 cartuchos, 1 arma hechiza y 11 armas punzocortantes.<\/p>\n<p>Con la participaci\u00f3n de la Fuerza Metropolitana Estatal (FME), Polic\u00eda Federal (PF) Polic\u00eda Ministerial del Estado (PME) y elementos de la Secretar\u00eda de la Defensa Nacional (Sedena), se mantienen los operativos que incluye la vigilancia con apoyo de un helic\u00f3ptero que sobrevuela la zona metropolitana.<\/p>\n<p>Finalmente la Secretar\u00eda de Seguridad P\u00fablica inform\u00f3 que se atendieron a trav\u00e9s de la l\u00ednea de emergencias 9-1-1 m\u00e1s de 2 mil 700 auxilios de distinto \u00edndole, e hizo un llamado a la poblaci\u00f3n para que de buen uso de este n\u00famero y eviten las bromas o falsas alarmas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Luis Potos\u00ed.- A trav\u00e9s de los operativos \u201cTrueno\u201d, \u201cProtector\u201d, \u201cAntialcohol\u201d y patrullaje terrestre y a\u00e9reo articulados por la Secretar\u00eda de Seguridad P\u00fablica del Gobierno del Estado (SSPE) as\u00ed como vigilancia en tiendas de conveniencia, en el Centro Hist\u00f3rico capitalino y de Abastos y en &hellip; <\/p>\n","protected":false},"author":1,"featured_media":21753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[],"class_list":["post-21751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=21751"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21751\/revisions"}],"predecessor-version":[{"id":21754,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21751\/revisions\/21754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/21753"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=21751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=21751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=21751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}