{"id":21766,"date":"2018-02-26T06:42:54","date_gmt":"2018-02-26T12:42:54","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=21766"},"modified":"2018-02-26T06:42:54","modified_gmt":"2018-02-26T12:42:54","slug":"localiza-dgspe-4-vehiculos-con-reporte-de-robo-uno-de-ellos-en-la-region-huasteca","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/localiza-dgspe-4-vehiculos-con-reporte-de-robo-uno-de-ellos-en-la-region-huasteca\/","title":{"rendered":"Localiza DGSPE 4 veh\u00edculos con reporte de robo, uno de ellos en la regi\u00f3n huasteca"},"content":{"rendered":"<p>San Luis Potos\u00ed.- Como parte del resultado al seguimiento que realizan Polic\u00edas de la Fuerza Metropolitana Estatal (FME) a las denuncias ciudadanas por robo de veh\u00edculos, cuatro unidades fueron localizadas y aseguradas.<\/p>\n<p>La primera unidad fue localizada en Paseo de Los Colorines y C\u00f3ndor, en la colonia Colorines, en donde se localiz\u00f3 un veh\u00edculo marca Dodge, tipo Atos, modelo 2001, color rojo; con reporte de robo del d\u00eda 20 de febrero del 2018,  en el fraccionamiento Colorines, el cual fue encontrado con da\u00f1os en la carrocer\u00eda y en el interior <\/p>\n<p>En calle Tomas Urbina y Adolfo L\u00f3pez Mateos, de  la colonia Divisi\u00f3n del Norte, se asegur\u00f3 un veh\u00edculo marca V.W., tipo sed\u00e1n, color azul marino, modelo 1993, placas de Estado de Quer\u00e9taro, con reporte de robo del d\u00eda 24 enero del a\u00f1o en curso, en el fraccionamiento Tangamanga. Al momento de su hallazgo se encontraba sin espejos retrovisores, equipo de sonido y sin acumulador. <\/p>\n<p>Por otra parte, Polic\u00edas Metropolitanos aseguraron en calle Arteaga y calzada de Guadalupe, del Barrio San Sebasti\u00e1n, un veh\u00edculo marca Nissan, tipo pick-up, modelo 1995, color blanco; tiene reporte de robo el d\u00eda 13 de febrero del 2018, en calles del fraccionamiento Dalias. Fue hallado sin equipo de sonido.<\/p>\n<p>Finalmente, en el municipio de Ciudad Valles, dentro de los recorridos de seguridad de Polic\u00edas Estatales sobre la calle Ley Federal de Trabajo y Articulo 123, del fraccionamiento Infonavit No. 2, se asegur\u00f3 un veh\u00edculo marca VW, tipo panel, color blanca, modelo 2016, con placas del estado Guanajuato, el cual al revisar en la base de datos del Centro de Control, Comando, Comunicaciones y C\u00f3mputo C-4, cuenta con reporte de robo desde el mes julio del 2016, en el estado de Michoac\u00e1n. <\/p>\n<p>Las cuatro unidades fueron puestas a disposici\u00f3n del Ministerio P\u00fablico del Fuero Com\u00fan.<\/p>\n<p>-0000- <\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Luis Potos\u00ed.- Como parte del resultado al seguimiento que realizan Polic\u00edas de la Fuerza Metropolitana Estatal (FME) a las denuncias ciudadanas por robo de veh\u00edculos, cuatro unidades fueron localizadas y aseguradas. La primera unidad fue localizada en Paseo de Los Colorines y C\u00f3ndor, en &hellip; <\/p>\n","protected":false},"author":1,"featured_media":21767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4,19],"tags":[],"class_list":["post-21766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio","category-policia"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=21766"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21766\/revisions"}],"predecessor-version":[{"id":21768,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21766\/revisions\/21768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/21767"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=21766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=21766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=21766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}