{"id":21788,"date":"2018-02-26T09:53:31","date_gmt":"2018-02-26T15:53:31","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=21788"},"modified":"2018-02-26T09:53:31","modified_gmt":"2018-02-26T15:53:31","slug":"slp-tiene-grandes-ventajas-para-atraer-inversiones-internacionales-especialista-aleman","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/slp-tiene-grandes-ventajas-para-atraer-inversiones-internacionales-especialista-aleman\/","title":{"rendered":"SLP tiene grandes ventajas para atraer inversiones internacionales: Especialista Alem\u00e1n"},"content":{"rendered":"<p>-Cuenta con un gobierno serio y honesto: Stephan Lina.<br \/>\n-Se podr\u00eda convertir en el segundo lugar en M\u00e9xico en recibir capitales germanos, considera.<\/p>\n<p>San Luis Potos\u00ed es atractivo para los inversionistas porque tiene las cualidades para desarrollar importantes proyectos, ya que cuenta con un gobierno serio y honesto que sabe promover sus fortalezas para atraer capitales internacionales, aunado a las ventajas que ofrece la entidad encabezada por el Gobernador del Estado Juan Manuel Carreras L\u00f3pez, asegur\u00f3 el especialista alem\u00e1n en temas econ\u00f3micos Stephan Lina, de Bayerischer Rundfunk, la cadena m\u00e1s importante de Alemania de comunicaciones.<\/p>\n<p>En entrevista durante su reciente visita a la entidad, destac\u00f3 que por ello nuestra entidad podr\u00eda ocupar el segundo lugar en M\u00e9xico como destino de las inversiones alemanas, como resultado de la promoci\u00f3n industrial, conexiones en infraestructura, talento humano y condiciones para el desarrollo de negocios.<\/p>\n<p>Sobre las inversiones b\u00e1varas en San Luis Potos\u00ed, encabezadas por BMW Group por m\u00e1s de mil millones de d\u00f3lares, dijo que \u00e9sta fortalecer\u00e1 las conexiones entre la entidad y aquel pa\u00eds, sobre todo en materia econ\u00f3mica, cultural, acad\u00e9micas o art\u00edsticas, estim\u00f3 que dentro de 10 a\u00f1os se contar\u00e1 con mayor presencia de empresas en la entidad, y compa\u00f1\u00edas potosinas en esta regi\u00f3n de Alemania.<\/p>\n<p>\u201cLa comunidad econ\u00f3mica e industrial alemana ahora conoce a San Luis Potos\u00ed, y va a llegar m\u00e1s visitantes por la manera en que el gobierno organiza inversiones, la fuerza trabajadora es excelente y su geograf\u00eda, tienen cercan\u00eda con ambos puertos y la carretera 57 que es parte de la ruta NAFTA\u201d, enfatiz\u00f3.<\/p>\n<p>En su visita a la entidad, el especialista en industria y finanzas destac\u00f3 que es una gran sorpresa ya que muchos de los integrantes de esta delegaci\u00f3n no conoc\u00edan el nivel de desarrollo ni de la econom\u00eda del pa\u00eds ni de la entidad. \u201cM\u00e9xico es muy industrializado, casi al nivel de los estados m\u00e1s avanzados como Corea del Sur o Alemania, es muy impresionante\u201d, destac\u00f3.<\/p>\n<p>De la presencia que tendr\u00e1 San Luis Potos\u00ed en la pr\u00f3xima feria de Hannover, puntualiz\u00f3 que es una oportunidad para que la comunidad internacional de periodistas especializados conozcan las condiciones de ofrecer la entidad para el desarrollo de proyectos de inversi\u00f3n.<\/p>\n<p>En consecuencia, reiter\u00f3 que otras empresas alemanas como BMW, Dr\u00e4xlmaier, Contienal o Bosh, continuar\u00e1n desarrollando sus proyectos de inversi\u00f3n ya que se tienen las condiciones para mantenerlas.<\/p>\n<p>Destac\u00f3 que nuestro pa\u00eds y San Luis Potos\u00ed son invitados a la feria Hannover Messe 2018, el encuentro industrial m\u00e1s importante del mundo que congrega a miles de empresario y periodistas de todo el mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Cuenta con un gobierno serio y honesto: Stephan Lina. -Se podr\u00eda convertir en el segundo lugar en M\u00e9xico en recibir capitales germanos, considera. San Luis Potos\u00ed es atractivo para los inversionistas porque tiene las cualidades para desarrollar importantes proyectos, ya que cuenta con un gobierno &hellip; <\/p>\n","protected":false},"author":1,"featured_media":21789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[],"class_list":["post-21788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=21788"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21788\/revisions"}],"predecessor-version":[{"id":21790,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21788\/revisions\/21790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/21789"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=21788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=21788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=21788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}