{"id":21798,"date":"2018-02-26T20:02:42","date_gmt":"2018-02-27T02:02:42","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=21798"},"modified":"2018-02-26T20:02:42","modified_gmt":"2018-02-27T02:02:42","slug":"orientaran-alcaldias-para-evitar-delitos-electorales","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/orientaran-alcaldias-para-evitar-delitos-electorales\/","title":{"rendered":"Orientar\u00e1n a alcald\u00edas para evitar delitos electorales  \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0"},"content":{"rendered":"<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>San Luis Potos\u00ed.- A fin de evitar que los ayuntamientos caigan en delitos electorales la Coordinaci\u00f3n Estatal para el Fortalecimiento Institucional de los Municipios (CEFIM) realizar\u00e1 en los 58 ayuntamientos asesor\u00edas para lo cual, convocar\u00e1n a los alcaldes a reuniones regionales donde ser\u00e1n expuestas las limitantes establecidas en la ley.<\/p>\n<p>Gerardo Aldaco, titular de la CEFIM, inform\u00f3 que los distintos cabildos ser\u00e1n convocados para participar en seminarios y cursos de orientaci\u00f3n e informaci\u00f3n respecto a lo estipulado para salvaguardar el proceso.<\/p>\n<p>Dijo que se busca que el proceso transcurra con madurez pol\u00edtica y en calma, con un clima social de convivencia sobre la base de un contacto y di\u00e1logo de respeto entre las diferentes ideolog\u00edas, en el entendido de que es inter\u00e9s com\u00fan el avance de nuestro estado.<\/p>\n<p>Asimismo, coment\u00f3 que se debe seguir impulsando a San Luis Potos\u00ed hacia mejores y mayores niveles de bienestar, con paz y armon\u00eda, prosperidad para todos con tranquilidad y paz social.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 San Luis Potos\u00ed.- A fin de evitar que los ayuntamientos caigan en delitos electorales la Coordinaci\u00f3n Estatal para el Fortalecimiento Institucional de los Municipios (CEFIM) realizar\u00e1 en los 58 ayuntamientos asesor\u00edas para lo cual, convocar\u00e1n a los alcaldes a reuniones regionales donde ser\u00e1n expuestas &hellip; <\/p>\n","protected":false},"author":1,"featured_media":21799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[],"class_list":["post-21798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=21798"}],"version-history":[{"count":2,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21798\/revisions"}],"predecessor-version":[{"id":21801,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21798\/revisions\/21801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/21799"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=21798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=21798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=21798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}