{"id":21812,"date":"2018-02-27T06:26:52","date_gmt":"2018-02-27T12:26:52","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=21812"},"modified":"2018-02-27T06:26:52","modified_gmt":"2018-02-27T12:26:52","slug":"aprueba-cabildo-cuenta-publica-de-enero-del-2018","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/aprueba-cabildo-cuenta-publica-de-enero-del-2018\/","title":{"rendered":"Aprueba cabildo cuenta p\u00fablica de enero del 2018.  \u00a0"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ciudad Valles.- Durante la sesi\u00f3n Ordinaria No. 75 del Cabildo de Ciudad Valles, realizada este lunes 26 de febrero en el sal\u00f3n \u201cRafael Curiel Gallegos\u201d, sus integrantes aprobaron la Cuenta P\u00fablica del mes de Enero del 2018.<\/p>\n<p>Los Estados Financieros correspondientes este mes de Enero, fueron presentados por el Tesorero Eliseo Moreno Hern\u00e1ndez, quien explic\u00f3 a todos los integrantes del cabildo lo correspondiente a cada una de las cuentas del activo y pasivo de las arcas municipales, plasmadas en los documentos.<\/p>\n<p>Les dio a conocer la reclasificaci\u00f3n de cuentas: lo que corresponde al adeudo con Instituci\u00f3n Financiera y lo que se refiere a sueldos y salarios. En la primera les record\u00f3 que de los 30 millones de pesos del pr\u00e9stamo solicitado en el 2016, solo quedan 10 millones que deber\u00e1 quedar pagado para el mes de Junio de este a\u00f1o.<\/p>\n<p>En lo que respecta a sueldos y salarios, les explic\u00f3 que esta cuenta que anteriormente se generalizaba ahora podr\u00e1 establecerse por departamento, lo que sin duda mejorar\u00e1 la revisi\u00f3n de la misma cuando se requiera.<\/p>\n<p>Para finalizar la Sesi\u00f3n Ordinaria los integrantes del Cabildo aprobaron por mayor\u00eda la cuenta p\u00fablica de Enero del 2018.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ciudad Valles.- Durante la sesi\u00f3n Ordinaria No. 75 del Cabildo de Ciudad Valles, realizada este lunes 26 de febrero en el sal\u00f3n \u201cRafael Curiel Gallegos\u201d, sus integrantes aprobaron la Cuenta P\u00fablica del mes de Enero del 2018. Los Estados Financieros correspondientes este mes de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":21813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,4],"tags":[],"class_list":["post-21812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=21812"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21812\/revisions"}],"predecessor-version":[{"id":21814,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21812\/revisions\/21814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/21813"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=21812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=21812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=21812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}