{"id":21827,"date":"2018-02-27T09:24:45","date_gmt":"2018-02-27T15:24:45","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=21827"},"modified":"2018-02-27T09:24:45","modified_gmt":"2018-02-27T15:24:45","slug":"coordinacion-para-operativos-de-prevencion-y-combate-la-delincuencia","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/coordinacion-para-operativos-de-prevencion-y-combate-la-delincuencia\/","title":{"rendered":"Coordinaci\u00f3n para operativos de prevenci\u00f3n y combate a la delincuencia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>San Luis Potos\u00ed.- El vicepresidente de la Comisi\u00f3n de Desarrollo Econ\u00f3mico y Social de la LXI Legislatura, diputado Mariano Ni\u00f1o Mart\u00ednez hizo un llamado a los diferentes niveles de gobierno para que \u201ccierren filas\u201d en el dise\u00f1o e implementaci\u00f3n de acciones y operativos para prevenir y combatir la delincuencia.<br \/>\nPuntualiz\u00f3 que \u201cactualmente la inseguridad es un tema prioritario que tiene que ser atendido coordinadamente entre los diferentes niveles de gobierno\u201d.<br \/>\nEl legislador Mariano Ni\u00f1o, se\u00f1al\u00f3 que no se puede soslayar que San Luis Potos\u00ed en estos momentos atraviesa por una situaci\u00f3n complicada de inseguridad ante los constantes asaltos, robos y ejecuciones.<br \/>\nSe\u00f1al\u00f3 que las autoridades tienen que dar resultados a la ciudadan\u00eda, para ello, deben trabajar con absoluta coordinaci\u00f3n para bajar los \u00edndices de inseguridad que se registran en la entidad.<br \/>\nEn lo que se refiere a las inversiones para San Luis Potos\u00ed, el legislador asegur\u00f3 que afortunadamente existen las condiciones para seguir atrayendo nuevas empresas a territorio potosino.<br \/>\nPor ello, \u201ces necesario combatir eficazmente a la delincuencia para generar confianza entre la ciudadan\u00eda y los empresarios para que mantengan sus programas de inversi\u00f3n que tienen contemplados para el estado de San Luis Potos\u00ed\u201d.<br \/>\nNi\u00f1o Mart\u00ednez, expuso que \u201cla cuesti\u00f3n de la inseguridad es un tema nacional y no es particular de San Luis Potos\u00ed, pero a fin del d\u00eda, se debe de trabajar para dar resultados inmediatos\u201d.<br \/>\n&#8212;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; San Luis Potos\u00ed.- El vicepresidente de la Comisi\u00f3n de Desarrollo Econ\u00f3mico y Social de la LXI Legislatura, diputado Mariano Ni\u00f1o Mart\u00ednez hizo un llamado a los diferentes niveles de gobierno para que \u201ccierren filas\u201d en el dise\u00f1o e implementaci\u00f3n de acciones y operativos para &hellip; <\/p>\n","protected":false},"author":1,"featured_media":21828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,11,4],"tags":[],"class_list":["post-21827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-congreso","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=21827"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21827\/revisions"}],"predecessor-version":[{"id":21829,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21827\/revisions\/21829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/21828"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=21827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=21827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=21827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}