{"id":21895,"date":"2018-03-01T08:56:14","date_gmt":"2018-03-01T14:56:14","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=21895"},"modified":"2018-03-01T08:56:14","modified_gmt":"2018-03-01T14:56:14","slug":"fme-detiene-cuatro-por-posesion-de-droga","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/fme-detiene-cuatro-por-posesion-de-droga\/","title":{"rendered":"FME \u00a0detiene a cuatro por posesi\u00f3n de droga  \u00a0  \u00a0"},"content":{"rendered":"<p>San Luis Potos\u00ed.- En recorridos de seguridad y vigilancia de Polic\u00edas de la Fuerza Metropolitana Estatal (FME), se detuvo a cuatro hombres, a quienes se les aseguraron varias bolsitas con droga conocida como cristal.<\/p>\n<p>La acci\u00f3n contra el delito se llev\u00f3 a cabo en Avenida Morales y Saucito y Avenida Hern\u00e1n Cort\u00e9s, donde Polic\u00edas Metropolitanos visualizaron un veh\u00edculo marca Ford, tipo Ka, color gris, modelo 2001, dentro del cual se encontraban varias personas con aparente actitud sospechosa.<\/p>\n<p>Al llevar a cabo la revisi\u00f3n de rutina, los elementos de seguridad localizaron dos bolsas de polietileno, una que conten\u00eda 500 gramos aproximadamente de una sustancia granulada, color blanco y otra bolsa con un peso aproximado de 189 gramos de una sustancia granulada, color rojo, ambas sustancias con las caracter\u00edsticas f\u00edsicas de la droga conocida como <em>cristal<\/em>.<\/p>\n<p>En esta acci\u00f3n, fueron detenidos quienes se identificaron como Ever F., de 29 a\u00f1os de edad, Jos\u00e9 H., de 30 a\u00f1os de edad, Mois\u00e9s F., de 37 a\u00f1os de edad y Edgar L., de 23 a\u00f1os de edad, a quienes\u00a0 se les comunic\u00f3 su derecho a guardar silencio y contar con un abogado.<\/p>\n<p>Los cuatro detenidos y la droga asegurada fueron puestos a disposici\u00f3n del Ministerio P\u00fablico del Fuero Federal.<\/p>\n<p>Ante estos hechos la SSPE, exhorta a la ciudadan\u00eda a seguir denunciando a las L\u00edneas de Emergencias 9-1-1 o 089 de Denuncia An\u00f3nima, cualquier hecho constitutivo del delito, esto con la finalidad de seguir coadyuvando con las autoridades a preservar la paz y la seguridad en el Estado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>-0000-<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Luis Potos\u00ed.- En recorridos de seguridad y vigilancia de Polic\u00edas de la Fuerza Metropolitana Estatal (FME), se detuvo a cuatro hombres, a quienes se les aseguraron varias bolsitas con droga conocida como cristal. La acci\u00f3n contra el delito se llev\u00f3 a cabo en Avenida &hellip; <\/p>\n","protected":false},"author":1,"featured_media":21858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4,19],"tags":[],"class_list":["post-21895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio","category-policia"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=21895"}],"version-history":[{"count":2,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21895\/revisions"}],"predecessor-version":[{"id":21897,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/21895\/revisions\/21897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/21858"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=21895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=21895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=21895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}