{"id":34289,"date":"2019-03-29T05:48:04","date_gmt":"2019-03-29T11:48:04","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=34289"},"modified":"2019-03-29T05:48:04","modified_gmt":"2019-03-29T11:48:04","slug":"inpode-lleva-activacion-fisica-a-planteles-de-educacion-basica","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/inpode-lleva-activacion-fisica-a-planteles-de-educacion-basica\/","title":{"rendered":"\u00a0 INPODE lleva activaci\u00f3n f\u00edsica a planteles de educaci\u00f3n b\u00e1sica  \u00a0"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>Dentro del Programa \u201cLa Seguridad es Compromiso de Todos\u201d<\/strong><\/li>\n<li><strong>Se visitaron dos planteles de primaria y uno de preescolar cuyos alumnos participaron de forma entusiasta<\/strong><strong style=\"font-size: 1rem;\">\u00a0<\/strong><\/li>\n<\/ul>\n<p>San Luis Potos\u00ed.- Para continuar con las acciones del Programa \u201cLa Seguridad es Compromiso de Todos\u201d, el Instituto Potosino del Deporte y Cultura F\u00edsica (INPODE), a trav\u00e9s de la Subdirecci\u00f3n de Deporte Social llev\u00f3 jornadas de activaci\u00f3n f\u00edsica a alumnos y alumnas de diversos planteles de educaci\u00f3n b\u00e1sica incluyendo preescolares.<\/p>\n<p>Los activadores acudieron en primer lugar a la Escuela Primaria \u201cJuli\u00e1n de los Reyes\u201d, donde m\u00e1s de 450 alumnos participaron de forma entusiasta en la jornada; ah\u00ed bailaron, realizaron ejercicios acordes a su edad y condici\u00f3n animados por el j\u00fabilo de los expositores que mostraban la manera de realizar las rutinas para que los menores las llevaran a cabo.<\/p>\n<p>La siguiente escuela que recibi\u00f3 al personal de Deporte Social del INPODE fue la Primaria \u201cManuel Jos\u00e9 Oth\u00f3n\u201d, cuya poblaci\u00f3n de 500 ni\u00f1os y ni\u00f1as vivieron una ma\u00f1ana diferente dentro de sus actividades cotidianas al participar de las rutinas; adem\u00e1s de celebrar la activaci\u00f3n, los profesionales del rubro recomendaron ampliamente a los mentores y encargados de la educaci\u00f3n f\u00edsica, celebrar de forma continua este tipo de sesiones.<\/p>\n<p>Posteriormente se visit\u00f3 al plantel de educaci\u00f3n preescolar \u201cLuis G. Medell\u00edn\u201d; los 200 ni\u00f1os y ni\u00f1as de dicha instituci\u00f3n fueron avisados de la visita de activadores, a la llegada del personal ya estaban ansiosos de trasladarse al patio de la escuela para hacer formaciones e iniciar la rutina.<\/p>\n<p>El apoyo de las notas musicales es de suma importancia ya que los participantes imitan los movimientos del activador bajo diversos ritmos.<\/p>\n<p>La gira por los centros educativos en el marco de este programa continuar\u00e1 con la presencia del Instituto Potosino de Cultura F\u00edsica y Deporte que llevar\u00e1 movimiento, alegr\u00eda, mensaje de salud e iniciaci\u00f3n al deporte a la ni\u00f1ez de San Luis Potos\u00ed.<\/p>\n<p>&#8212;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Dentro del Programa \u201cLa Seguridad es Compromiso de Todos\u201d Se visitaron dos planteles de primaria y uno de preescolar cuyos alumnos participaron de forma entusiasta\u00a0 San Luis Potos\u00ed.- Para continuar con las acciones del Programa \u201cLa Seguridad es Compromiso de Todos\u201d, el Instituto Potosino &hellip; <\/p>\n","protected":false},"author":1,"featured_media":34290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,5],"tags":[],"class_list":["post-34289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/34289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=34289"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/34289\/revisions"}],"predecessor-version":[{"id":34291,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/34289\/revisions\/34291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/34290"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=34289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=34289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=34289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}