{"id":40558,"date":"2019-10-21T21:31:14","date_gmt":"2019-10-22T03:31:14","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=40558"},"modified":"2019-10-21T21:31:14","modified_gmt":"2019-10-22T03:31:14","slug":"anuncia-aec-rehabilitacion-de-importante-camino-en-la-zona-tenek","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/anuncia-aec-rehabilitacion-de-importante-camino-en-la-zona-tenek\/","title":{"rendered":"Anuncia AEC rehabilitaci\u00f3n de importante camino en la zona T\u00e9nek."},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ciudad Valles.-\u00a0 Se rindieron los honores a la bandera en la escuela telesecundaria \u201cBenito Ju\u00e1rez\u201d del ejido La Lima, en el coraz\u00f3n de la zona T\u00e9nek de Ciudad Valles.<\/p>\n<p>El director del plantel Juan Mariscal Jim\u00e9nez recibi\u00f3 al alcalde Adri\u00e1n Esper C\u00e1rdenas y a diversos funcionarios municipales.<\/p>\n<p>Despu\u00e9s de los honores a los s\u00edmbolos patrios el alcalde cedi\u00f3 la voz a los titulares de CODESOL y de Obras P\u00fablicas; Alberto Esp\u00ednola Maldonado y Alberto Machuca anunciaron la rehabilitaci\u00f3n de\u00a0 la calle que pasa frente a la escuela, obra que tambi\u00e9n beneficiar\u00e1 a pacientes de la cl\u00ednica.<\/p>\n<p>El presidente municipal en su mensaje a los alumnos, remarc\u00f3 la importancia de la sustentabilidad que \u00e9l est\u00e1 impulsando. Dijo que en los pr\u00f3ximos veinte meses entregar\u00e1 parte del trazo de la v\u00eda peatonal que beneficiar\u00eda a cientos de vallenses.<\/p>\n<p>Ah\u00ed mismo el alcalde entreg\u00f3 tres tabletas electr\u00f3nicas a j\u00f3venes destacados: Gabriela Hern\u00e1ndez Hern\u00e1ndez, Gloria Santana Castro y \u00c1ngel Hern\u00e1ndez Santos.<\/p>\n<p>El regidor de Hacienda Guadalupe Arteaga habl\u00f3 respecto a la importancia de cuidar los recursos; ahora lo que se ahorra en la administraci\u00f3n municipal se aplica en beneficio de los ciudadanos.<\/p>\n<p>El alcalde cedi\u00f3 el micr\u00f3fono a estudiantes de los planteles escolares quienes le solicitaron impermeabilizar y pintar sus aulas; tambi\u00e9n le pidieron ventiladores para la telesecundaria y techar las gradas de la cancha en la preparatoria Juan Moreno Cort\u00e9s.<\/p>\n<p>El alcalde visit\u00f3 los planteles para analizar la posibilidad de realizar las acciones que piden los alumnos.<\/p>\n<p>&#8212;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ciudad Valles.-\u00a0 Se rindieron los honores a la bandera en la escuela telesecundaria \u201cBenito Ju\u00e1rez\u201d del ejido La Lima, en el coraz\u00f3n de la zona T\u00e9nek de Ciudad Valles. El director del plantel Juan Mariscal Jim\u00e9nez recibi\u00f3 al alcalde Adri\u00e1n Esper C\u00e1rdenas y a &hellip; <\/p>\n","protected":false},"author":1,"featured_media":40559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,4],"tags":[],"class_list":["post-40558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/40558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=40558"}],"version-history":[{"count":2,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/40558\/revisions"}],"predecessor-version":[{"id":40561,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/40558\/revisions\/40561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/40559"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=40558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=40558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=40558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}