{"id":4227,"date":"2013-08-01T16:45:48","date_gmt":"2013-08-01T22:45:48","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2013\/08\/01\/inicia-municipio-censo-al-ejido-plan-de-ayala-y-fraccionamiento-buenos-aires\/"},"modified":"2013-08-01T16:45:48","modified_gmt":"2013-08-01T22:45:48","slug":"inicia-municipio-censo-al-ejido-plan-de-ayala-y-fraccionamiento-buenos-aires","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/inicia-municipio-censo-al-ejido-plan-de-ayala-y-fraccionamiento-buenos-aires\/","title":{"rendered":"INICIA MUNICIPIO CENSO AL EJIDO PLAN DE AYALA Y FRACCIONAMIENTO BUENOS AIRES"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><span style=\"line-height: 1.3em;\">&#8211; <\/span><span style=\"line-height: 1.3em;\">Hay entendimiento y se avanza sin violencia<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Ciudad Valles S.L.P.- El Secretario del Ayuntamiento, Gilberto Almend\u00e1rez Mar\u00edn, dio a conocer que personal del ayuntamiento comenz\u00f3 el levantamiento del censo entre los habitantes del Ejido Plan de Ayala y Fraccionamiento Buenos Aires, fungiendo as\u00ed como intermediario para tratar de solucionar este problema que persiste desde hace varios a\u00f1os.<\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.3em;\">Expuso que el censo, por parte de la Administraci\u00f3n, es un compromiso \u00fanico e imparcial para poder determinar cu\u00e1ntas personas habitan ah\u00ed y posteriormente entregar la informaci\u00f3n a las instancias correspondientes y de ser posible proceder al reconocimiento de los derechos de las personas y en su caso gestionar la indemnizaci\u00f3n al propietario de los inmuebles, que en este caso es el Ejido Plan de Ayala, de cuya extensi\u00f3n total de 60 hect\u00e1reas, se calcula est\u00e1n afectadas 30.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.3em;\">El Secretario del Ayuntamiento dej\u00f3 en claro que a\u00fan no se establecen condiciones ni montos para esa indemnizaci\u00f3n, pues para ellos se buscar\u00e1 la intervenci\u00f3n de las autoridades federales y estatales; sin embargo resalt\u00f3 que los m\u00e1s rescatable de esta acci\u00f3n es que dirigentes y personas implicadas en esta situaci\u00f3n entran a una etapa de di\u00e1logo y entendimiento, sin violencia y sin conflictos sociales, luego de que incluso se tuvo una reuni\u00f3n en donde los l\u00edderes de Plan de Ayala y de Buenos Aires exhortaron a sus representados a la tranquilidad y la paciencia, de tal forma que hasta la tarde de este d\u00eda la actividad se desarrollaba en completa calma. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Hay entendimiento y se avanza sin violencia Ciudad Valles S.L.P.- El Secretario del Ayuntamiento, Gilberto Almend\u00e1rez Mar\u00edn, dio a conocer que personal del ayuntamiento comenz\u00f3 el levantamiento del censo entre los habitantes del Ejido Plan de Ayala y Fraccionamiento Buenos Aires, fungiendo as\u00ed como &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-4227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/4227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=4227"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/4227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=4227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=4227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=4227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}