{"id":4303,"date":"2013-08-13T14:00:57","date_gmt":"2013-08-13T20:00:57","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2013\/08\/13\/pujal-coy-sera-detonante-de-la-economia-de-la-planicie-huasteca-huerta-valdez\/"},"modified":"2013-08-13T14:00:57","modified_gmt":"2013-08-13T20:00:57","slug":"pujal-coy-sera-detonante-de-la-economia-de-la-planicie-huasteca-huerta-valdez","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/pujal-coy-sera-detonante-de-la-economia-de-la-planicie-huasteca-huerta-valdez\/","title":{"rendered":"PUJAL COY SERA DETONANTE DE LA ECONOMIA DE LA PLANICIE HUASTECA:  HUERTA VALDEZ"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.3em;\"><strong>-La legisladora informo quedara inicio la primer etapa del Proyecto Pujal Coy<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">San Luis Potos\u00b4.- La Coordinadora de los Diputados del PRI en el Congreso del Estado, Rosa Mar\u00eda Huerta Valdez, inform\u00f3 que gracias a las gestiones que ha realizado el Gobierno del Estado, va a dar inicio la primera etapa del Proyecto Pujal Coy, el cual incluye una inversi\u00f3n de 110 millones de pesos.<\/p>\n<p style=\"text-align: justify;\">La legisladora se\u00f1al\u00f3 que este proyecto ser\u00e1 detonante y una acci\u00f3n concreta para mejorar la econom\u00eda de los pobladores de los municipios de la Huasteca como \u00c9bano, Tamu\u00edn y San Vicente Tancuayalab.<\/p>\n<p style=\"text-align: justify;\">\u201cEs un proyecto muy ambicioso y estas son las obras que est\u00e1n concretando tanto el Gobernador del Estado, Fernando Toranzo Fern\u00e1ndez y el Presidente de la Rep\u00fablica, Enrique Pe\u00f1a Nieto, porque no vamos a estar dando mejoralitos para el desempleo se est\u00e1n concretando proyectos que van a reactivar la econom\u00eda de la zona y del distrito\u201d.<\/p>\n<p style=\"text-align: justify;\">Huerta Valdez, indic\u00f3 que este proyecto se le present\u00f3 al entonces candidato y ahora presidente de la Rep\u00fablica, Enrique Pe\u00f1a Nieto, el cual lo estudi\u00f3 y aprob\u00f3 dicho proyecto que ha sido impulsado por el Gobierno del Estado.<\/p>\n<p style=\"text-align: justify;\">\u201cHoy es una realidad que se ve reflejada con la inversi\u00f3n en la primera etapa de esta magna obra del sistema de riego del Pujal-Coy, con ciento diez millones de pesos, con esto se habla no s\u00f3lo de palabras, sino de hechos\u201d, a\u00f1adi\u00f3.<\/p>\n<p style=\"text-align: justify;\">\u201cEn el ejido Ponciano Arriaga, la activaci\u00f3n y modernizaci\u00f3n del Proyecto Pujal Coy es un compromiso del campa\u00f1a del entonces Presidente de la Rep\u00fablica, Enrique Pe\u00f1a Nieto, y sin duda se har\u00e1 realidad gracias al impulso que le est\u00e1 dando el gobernador del estado, Fernando Toranzo Fern\u00e1ndez, quien ha estado de manera constante gestionando recursos para que este proyecto se logre\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>-La legisladora informo quedara inicio la primer etapa del Proyecto Pujal Coy San Luis Potos\u00b4.- La Coordinadora de los Diputados del PRI en el Congreso del Estado, Rosa Mar\u00eda Huerta Valdez, inform\u00f3 que gracias a las gestiones que ha realizado el Gobierno del Estado, va &hellip; <\/p>\n","protected":false},"author":1,"featured_media":4302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/4303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=4303"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/4303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/4302"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=4303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=4303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=4303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}