{"id":4397,"date":"2013-09-06T15:10:50","date_gmt":"2013-09-06T21:10:50","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2013\/09\/06\/el-campo-de-la-huasteca-en-ruina-por-dudosa-aplicacion-de-recursos-del-fofaes\/"},"modified":"2013-09-06T15:10:50","modified_gmt":"2013-09-06T21:10:50","slug":"el-campo-de-la-huasteca-en-ruina-por-dudosa-aplicacion-de-recursos-del-fofaes","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/el-campo-de-la-huasteca-en-ruina-por-dudosa-aplicacion-de-recursos-del-fofaes\/","title":{"rendered":"EL CAMPO DE LA HUASTECA EN RUINA POR DUDOSA APLICACI\u00d3N DE RECURSOS DEL \u201cFOFAES\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.3em;\"><strong>&#8211; Aseguran que dirigentes de organizaciones en forma particular reciben a\u00f1o con a\u00f1o proyectos pero sus representados \u201cno\u201d.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.3em;\"><strong>&#8211; Universidad de Coahuila hace estudios de diagnostico del campo a\u00f1o con a\u00f1o, y quienes conocen la realidad son las universidades potosinas.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.3em;\">Ciudad Valles S.L.P.- La distribuci\u00f3n de los recursos federales para apoyar el campo mexicano por parte de la Secretar\u00eda de Agricultura Ganader\u00eda Pesca y Alimentaci\u00f3n \u00a0a trav\u00e9s del la Secretaria de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos mediante el Programa en Concurrencia del Estado de San Luis Potos\u00ed, deja muchas interrogantes aseguran productores de la zona Huasteca.<\/span><\/p>\n<p style=\"text-align: justify;\">Cansados de hacer tramites para acceder a apoyos de SAGARPA para hacer producir sus tierras, productores agropecuarios denunciaron a este medio un sin n\u00famero de irregularidades en que incurre SAGARPA y SEDARH para asignar los recursos, los cuales solo se entregan a destacados pol\u00edticos, a dirigentes de organismos ganaderos, ca\u00f1eros entre otros quienes los reciben \u00a0a titulo personal, y uno que otro afortunado que recibe apoyos miserables de $9,000 contra millones.<\/p>\n<p style=\"text-align: justify;\">Los quejosos que pidieron mantener sus identidades en el anonimato, se\u00f1alan que la Huasteca potosina viven la peor de sus crisis econ\u00f3micas, al contar con funcionarios corruptos que lo menos que les interesa es hacer producir la tierra, que controlan los recursos federales a su antojo y solo liberan proyectos para comprar el silencio de dirigentes de organizaciones a trav\u00e9s de un consejo denominado FOFAES (Fondo de Fomento Agropecuario del Estado).<\/p>\n<p style=\"text-align: justify;\">Desde el 2011 que no se apoya al campo de la zona Huasteca, y solo se han apoyado en forma selectiva a pol\u00edticos o dirigentes de organizaciones, pero a los verdaderos productores aun siguen esperando se les atienda sus proyectos, por el contrario los hacen gastar en inversiones, t\u00e9cnicos, con la promesa que al final del a\u00f1o SAGARPA les autorizara su proyecto con apoyos del 50% y 75% pero pasan a\u00f1os y despu\u00e9s les piden firme un documento donde manifiesta que ya no les interesa el proyecto pero toda la documentaci\u00f3n del proyecto, facturas de equipamiento nunca regresan.<\/p>\n<p style=\"text-align: justify;\">Se\u00f1alan que es lamentable que el FOFAES contrate a la Universidad Aut\u00f3noma Agraria \u201cAntonio Narro\u201d, para que cada a\u00f1o \u201celabore\u201d supuestos estudios de diagnostico del sector rural de San Luis Potos\u00ed, haciendo un informe que nadie conoce, cuando en San Luis Potos\u00ed se tiene la UASLP, Tecnol\u00f3gicos y otras universidades que pueden hacer un verdadero estudio de las necesidades del campo potosino, ya que esa universidad por Internet se localiza en calzada Antonio Narro 1923 zona sin asignaci\u00f3n de nombre ni colonia en Saltillo Coahuila de Zaragoza y es ese plantel quien esta determinando el rumbo de productores agropecuarios pero se desconoce completamente su metodolog\u00eda para hacer a\u00f1o con a\u00f1o estudios del campo potosino.<\/p>\n<p style=\"text-align: justify;\">Programa de apoyo a la inversi\u00f3n en equipamiento e infraestructura Agr\u00edcola, Ganadero y Pesca, contempla proyectos para apoyar la adquisici\u00f3n de Corrales, borregos, sala de orde\u00f1a, cercos, equipos de bombeo, equipos de riego para ganado y agr\u00edcola, tractores, remolques, equipo e infraestructura, proyecto de hasta $750 000 donde se apoya al productor con un porcentaje, pero si esos apoyos realmente llegaran al productor no se tendr\u00edan el problema de desabasto de ganado para las empacadoras Romar, GUSI que est\u00e1n a punto de cerrar, los agricultores no tendr\u00edan que estar malbaratando sus granos en Tamaulipas o los Ca\u00f1eros no estuvieran viviendo la peor de sus crisis economicas.<\/p>\n<p style=\"text-align: justify;\">Enfatizaron que son muchas las irregularidades con que se manejan todos los integrantes del FOFAES y lo han realizado por a\u00f1os, para prueba basta mencionar el programa 2013 que para estas fechas debi\u00f3 haberse aplicado al 100% ya que a finales del mes de noviembre de este a\u00f1o se tiene que hacer la comrpobaci\u00f3n y cerrar todo como lo marca la narma, pero a 2 meses, solo han enviado la revisi\u00f3n del proyecto particular con folio 851 del conocido exdiputado local, dirigente de MOCACO y actual presidente de la Asociaci\u00f3n Ganadera Local de Tamuin, Jos\u00e8 Luis Ramiro Galero quien tiene mas necesidad que los cientos de ganaderos que representa en ese municipio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Aseguran que dirigentes de organizaciones en forma particular reciben a\u00f1o con a\u00f1o proyectos pero sus representados \u201cno\u201d. &#8211; Universidad de Coahuila hace estudios de diagnostico del campo a\u00f1o con a\u00f1o, y quienes conocen la realidad son las universidades potosinas. Ciudad Valles S.L.P.- La distribuci\u00f3n &hellip; <\/p>\n","protected":false},"author":1,"featured_media":4396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/4397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=4397"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/4397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/4396"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=4397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=4397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=4397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}