{"id":5658,"date":"2014-05-21T13:38:10","date_gmt":"2014-05-21T19:38:10","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2014\/05\/21\/el-panoramico-5\/"},"modified":"2014-05-21T13:38:10","modified_gmt":"2014-05-21T19:38:10","slug":"el-panoramico-5","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/el-panoramico-5\/","title":{"rendered":"El Panoramico"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"line-height: 1.3em;\">Asi es todo se paga en la vida, usted se dio cuenta que no esta Televisa en la Final? Pues yo si, bendito sea Dios dejas de escuchar a los comentaristas con nombres y apodos burlones Pollo, Vaca y compa\u00f1\u00eda viendo y oyendo voces mas frescas como romacnoli, rosique, garcia y el brother Campos, los mejores comentaristas de Mexico, Felicidaddes y deseo recordarles a mis lectores que no soy profeta en mi tierra y les comente en lineas anteriores que el equipo Atletico de Madrid erael unico que sabe el sistema de el barcelona y que se coronaria y ah\u00ed esta, Felicidades Campeon, pero viene el sabado \u00a024 de mayo, se jugara la orejona Real Madrid vs Atletico de Madrid saliendo avante mi equipo merengue, ustedes seran testigos \u00a0de mi columna.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Volviendo a nuestro fut-bol nacional como se los eh comentado siempre da verg\u00fcenza 17 partidos de liga que los actores \u201cjugadores\u201d nos dan atole con el dedo, juegan como quieren y como pueden y si llegan a la liguilla aunque sea de panzaso pues ya la hicieron, ese nuevo torneo \u201cliguilla\u201d juegan diferente, que pasa con la federacion en donde deben de ponerse las pilas y castigar a los jugadores para que se pongan a jugar desde el primer minuto de el primer partido , ah pero no, la federacion debe de multar a los directivos, empresarios, due\u00f1os y todos los que pertenecen a una liga tan mediocre como la nuestra liga MX o liga Bancomer se los dejo de tarea. Pero como soy profeta en mi tierra todos los ganadores como el Atletico de Madrid y el Leon en Mexico fueron los que se coronaron, como la ve? Y no soy mago pero parece que si sabemos de futbol nacional e internacional, a ver si un periodico de renombre me contrata, jajajaja.<\/p>\n<p style=\"text-align: justify;\">Pues Felicidades al equipo Bicampeon de Mexico, el Leon, pues parece que quedar en el octavo lugar y jugar la liguilla de panzaso es el equipo ganador, pues dejo fuera a los mejores, lastima que no jueguen toda la temporada como la liguilla, porque en clavados tambien los mexicanos estan a la altura como en tiro al arco, como en tenis nacional una mexicana anda haciendo ruido como en racketbol, nuestra potosina la campeona para mucho rato Paola Longoria que no la supo cuidar, bueno ni permiso le dio el INPODE para que entrenara la vio roket Las Lomas le permitio entrenar y hay estan las consecuencias mas adelante el estado de Nuevo Leon le abrio sus brazos y hay esta la estrella potosina brillando mundialmente.<\/p>\n<p style=\"text-align: justify;\">Tambien quiero comentar como van las bebidas alcoholicas en los campos de juego les siguen tocando buenas ganancias a sus presidentes de ligas pues claro que si y los que los niegan son los mas corruptos jajaja y luego se enojan aproposito ya le andaba pegando a una quiniela este fin de semana pero me paso como en la feria que dicen \u201cpa la otra dijo el de los aros\u201d pero eso es lo de menos el problema son las batallas campales entre porras de equipos y como siempre se dice hay familia en los estadios en este caso en los campos de juego.<\/p>\n<p style=\"text-align: justify;\">Por otro lado estoy invitando a mis amigos de la CONADE como es el director el Lic. Jesus mena y mi amigo el Lic. Alejandro Reyes a mi cumplea\u00f1os numero ya no me acuerdo jajaja para que me hablen por telefono este 26 de mayo de 2 a 3 pm al 4813820160 radio panoramica, cabina para una felicitacion claro tambien a mi amigo Armando director del INPODE saludos y esteramos pendientes.<\/p>\n<p style=\"text-align: justify;\">Vamonos Arriba las Chivas, los rudos los rudos, los rudos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asi es todo se paga en la vida, usted se dio cuenta que no esta Televisa en la Final? Pues yo si, bendito sea Dios dejas de escuchar a los comentaristas con nombres y apodos burlones Pollo, Vaca y compa\u00f1\u00eda viendo y oyendo voces mas &hellip; <\/p>\n","protected":false},"author":1,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-5658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/5658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=5658"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/5658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=5658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=5658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=5658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}