{"id":61007,"date":"2021-11-08T19:28:27","date_gmt":"2021-11-09T01:28:27","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=61007"},"modified":"2021-11-08T19:28:27","modified_gmt":"2021-11-09T01:28:27","slug":"detecta-cea-saqueos-millonarios-en-todo-el-estado","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/detecta-cea-saqueos-millonarios-en-todo-el-estado\/","title":{"rendered":"Detecta CEA saqueos millonarios en todo el estado"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>Existen proyectos h\u00eddricos que no fueron terminados o que simplemente no operan, denunci\u00f3 Luis Fernando G\u00e1mez, director de la Comisi\u00f3n Estatal del Agua. <\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>San Luis Potos\u00ed.- Como resultado de la investigaci\u00f3n que por instrucciones del Gobernador Ricardo Gallardo Cardona se realiza al trabajo reportado por autoridades de la anterior administraci\u00f3n gubernamental, en la Comisi\u00f3n Estatal del Agua (CEA) se detect\u00f3 y document\u00f3 el saqueo millonario de recursos p\u00fablicos, a trav\u00e9s de proyectos inacabados, inexistentes o que no tienen la funcionalidad debida, engrosando la llamada herencia maldita.<\/p>\n<p>\u201cLa CEA no era la caja chica, sino la caja grandotota de la ex administraci\u00f3n\u201d, declar\u00f3 el titular del organismo, Luis Fernando G\u00e1mez Mac\u00edas, y se\u00f1al\u00f3 que las irregularidades resultaron peor de lo que se imagin\u00f3, lo que provoc\u00f3 que, seg\u00fan datos de Consejo Nacional de la Pol\u00edtica de Desarrollo Social (Coneval), se tenga un d\u00e9ficit del 25 % de la poblaci\u00f3n en materia de accesos a los servicios b\u00e1sicos de agua y saneamiento en el Estado.<\/p>\n<p>A\u00f1adi\u00f3 que la situaci\u00f3n lamentable en que la CEA se encuentra ser\u00e1 atendida por indicaciones del Gobernador Ricardo Gallardo Cardona, para lo cual ya se trabaja en un magno programa h\u00eddrico para garantizar el acceso al agua potable a toda la ciudadan\u00eda de San Luis Potos\u00ed.<\/p>\n<p>Entre las anomal\u00edas denunciadas se encuentra el caso de la Presa El Realito, a la que se le destinaron 5,100 millones de pesos, pero que de manera frecuente presenta fallas en el suministro que dejan sin agua a 250 mil habitantes de la zona Metropolitana de San Luis Potos\u00ed.<\/p>\n<p>En el Altiplano, al proyecto de la Presa La Maroma se destinaron 386 millones de pesos, pero no existe la obra ni caminos ni nada, adem\u00e1s de que no aparecen 100 millones de pesos ya que no se tiene registro de su destino.<\/p>\n<p>En la Huasteca se erogaron recursos millonarios para la construcci\u00f3n de plantas tratadoras de agua que nunca se construyeron o nunca entraron en funcionamiento; en la de Matlapa se destinaron 19 millones de pesos; en la de Xilitla 10 millones; en la del Centro de Reinserci\u00f3n Social de Ciudad Valles un mill\u00f3n de pesos y en la del Xolol 2.4 millones de pesos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Existen proyectos h\u00eddricos que no fueron terminados o que simplemente no operan, denunci\u00f3 Luis Fernando G\u00e1mez, director de la Comisi\u00f3n Estatal del Agua. &nbsp; San Luis Potos\u00ed.- Como resultado de la investigaci\u00f3n que por instrucciones del Gobernador Ricardo Gallardo Cardona se realiza al trabajo &hellip; <\/p>\n","protected":false},"author":1,"featured_media":61008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,23,11,4,12,5],"tags":[],"class_list":["post-61007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-congreso","category-estado","category-inicio","category-nacional","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/61007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=61007"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/61007\/revisions"}],"predecessor-version":[{"id":61009,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/61007\/revisions\/61009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/61008"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=61007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=61007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=61007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}