{"id":62874,"date":"2021-12-19T07:06:42","date_gmt":"2021-12-19T13:06:42","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=62874"},"modified":"2021-12-19T07:06:42","modified_gmt":"2021-12-19T13:06:42","slug":"soledenses-celebran-navidad-con-los-invasores-de-nuevo-leon","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/soledenses-celebran-navidad-con-los-invasores-de-nuevo-leon\/","title":{"rendered":"Soledenses celebran navidad con los Invasores de Nuevo Le\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>Cientos de familias de la zona Metropolitana se dieron cita en el Jard\u00edn principal, para disfrutar de \u00e9xitos musicales del solista Lenin Ram\u00edrez y Los Invasores de Nuevo Le\u00f3n. Las y los ni\u00f1os recibieron juguetes por parte de \u201cSanta Claus\u201d. <\/strong><\/li>\n<li><strong>Al comienzo del a\u00f1o 2022, dar\u00e1n inicio nuevos programas de ayuda social a estudiantes, personas con discapacidad, madres solteras y adultos mayores, adelant\u00f3 el Gobernador potosino Ricardo Gallardo Cardona. <\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Soledad de Graciano S\u00e1nchez se convirti\u00f3 en el escenario perfecto para llevar a cabo la quinta magna posada navide\u00f1a dentro del Festival de Invierno 2021, que organiza el Gobierno del Estado de San Luis Potos\u00ed, como una opci\u00f3n para fortalecer en la ciudadan\u00eda la uni\u00f3n familiar y fraternidad durante las fechas decembrinas.<\/p>\n<p>En esta ocasi\u00f3n, le toc\u00f3 al solista Len\u00edn Ram\u00edrez y a Los Invasores de Nuevo Le\u00f3n encender el \u00e1nimo de las y los potosinos.<\/p>\n<p>Ante cientos de familias, principalmente de la zona Metropolitana, que se dieron cita en el Jard\u00edn principal y respetando los protocolos y recomendaciones de prevenci\u00f3n sanitaria, el Mandatario Estatal Ricardo Gallardo Cardona les expres\u00f3 que las posadas navide\u00f1as son un esfuerzo de la administraci\u00f3n estatal para llevar momentos de alegr\u00eda, entretenimiento y sana convivencia a todo el territorio potosino, y les pidi\u00f3 disfrutarlas \u201cporque son de ustedes, para ustedes, pueblo de San Luis Potos\u00ed\u201d.<\/p>\n<p>En su mensaje, record\u00f3 que los programas de Licencias y Placas Gratuitas se encuentran disponibles en toda la Entidad en beneficio de las y los habitantes, para que la econom\u00eda en los hogares no se vea afectada por estos impuestos que antes eran onerosos; tambi\u00e9n adelant\u00f3 que iniciado el a\u00f1o 2022 inmediatamente se dar\u00e1 comienzo a nuevos proyectos de ayuda social como Pensiones a adultos mayores, apoyos econ\u00f3micos a madres solteras, Becas Escolares a las y los j\u00f3venes, as\u00ed como Becas econ\u00f3micas a personas con discapacidad.<\/p>\n<p>Posteriormente, Ricardo Gallardo entreg\u00f3 cobertores a familias vulnerables para que puedan enfrentar la temporada invernal, tambi\u00e9n hizo la entrega de juguetes a todos los ni\u00f1os y ni\u00f1as presentes, que, acompa\u00f1ado de \u201cSanta Claus\u201d provoc\u00f3 alegr\u00eda y emoci\u00f3n en sus rostros.<\/p>\n<p>Leonor Noyola, alcaldesa de Soledad de Graciano S\u00e1nchez, resalt\u00f3 el compromiso incansable del ayuntamiento para impulsar el desarrollo econ\u00f3mico y social de las familias soledenses, lo cual continuar\u00e1 favorablemente el pr\u00f3ximo 2022. Dese\u00f3 que la magia de la Navidad permee en cada uno de los hogares del municipio y subray\u00f3 que la conjunci\u00f3n de esfuerzos e ideas hacen m\u00e1s sencillos los problemas que puedan enfrentarse en el d\u00eda a d\u00eda.<\/p>\n<p>Enseguida, comenz\u00f3 el tan esperado espect\u00e1culo musical a cargo de Len\u00edn Ram\u00edrez, que con su peculiar banda arranc\u00f3 con \u201cEl Sinaloense\u201d, \u201cYo Ya No Vuelvo Contigo\u201d y \u201cEl Muchacho Alegre\u201d. La velada tom\u00f3 fuerza al presentarse los grandes exponentes de la m\u00fasica norte\u00f1a Los Invasores de Nuevo Le\u00f3n, quienes arrancaron suspiros y gritos de jovencitas con \u201cAguanta Coraz\u00f3n\u201d, \u201cGolpe de Suerte\u201d, \u201cNo Te Rindas Coraz\u00f3n\u201d, entre muchas m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Cientos de familias de la zona Metropolitana se dieron cita en el Jard\u00edn principal, para disfrutar de \u00e9xitos musicales del solista Lenin Ram\u00edrez y Los Invasores de Nuevo Le\u00f3n. Las y los ni\u00f1os recibieron juguetes por parte de \u201cSanta Claus\u201d. Al comienzo del a\u00f1o &hellip; <\/p>\n","protected":false},"author":1,"featured_media":62875,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[],"class_list":["post-62874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=62874"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62874\/revisions"}],"predecessor-version":[{"id":62876,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62874\/revisions\/62876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/62875"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=62874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=62874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=62874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}