{"id":62896,"date":"2021-12-19T21:24:56","date_gmt":"2021-12-20T03:24:56","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=62896"},"modified":"2021-12-19T21:24:56","modified_gmt":"2021-12-20T03:24:56","slug":"gobernador-ricardo-gallardo-lleva-la-navidad-a-personas-privadas-de-la-libertad","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/gobernador-ricardo-gallardo-lleva-la-navidad-a-personas-privadas-de-la-libertad\/","title":{"rendered":"Gobernador Ricardo Gallardo lleva la navidad a personas privadas de la libertad"},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>La banda de rock \u201cEl Gran Silencio\u201d puso a bailar y cantar a personas en el Centro de Reinserci\u00f3n Social y a sus familias.<\/strong><\/li>\n<li><strong> Acompa\u00f1ado por la Presidenta del Sistema Estatal para el Desarrollo Integral de la Familia Ruth Gonz\u00e1lez Silva entregan juguetes, dulces, regalos y cobertores.<\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<p>El Gobernador Ricardo Gallardo Cardona contin\u00faa rompiendo paradigmas y este domingo volvi\u00f3 a convivir con las Personas Privadas de la Libertad (PPL), durante la posada que les organiz\u00f3 dentro del Centro Estatal de Reinserci\u00f3n Social (CERESO) de La Pila, que cont\u00f3 con la presentaci\u00f3n de la banda \u201cEl Gran Silencio\u201d, donde comieron pizzas y se entregaron obsequios.<\/p>\n<p>El Mandatario Estatal acompa\u00f1ado por la Presidenta del Sistema Estatal para el Desarrollo Integral\u00a0 de la Familia (DIF) Ruth Gonz\u00e1lez Silva, fueron recibidos entre aplausos de las PPL, saludando a muchas de ellas quienes se acercaban a la pareja para hacerles alguna petici\u00f3n personal pero tambi\u00e9n para agradecerles el apoyo que desde el primer d\u00eda les ha brindado el nuevo Gobierno.<\/p>\n<p>El titular del Ejecutivo sigue cumpliendo su objetivo de gobernar para todas y todos, incluidas las personas que est\u00e1n en prisi\u00f3n, por ello demostr\u00f3 su calidez y su fraternidad al convivir con mujeres y hombres que cumplen una condena y llevarles sana convivencia, m\u00fasica, alimentos, cobertores y regalos para sus hijos e hijas a quienes se les permiti\u00f3 el acceso\u00a0 a dicho centro para que convivieran en familia en esta Navidad que es diferente porque las y los potosinos tienen un Gobierno diferente.<\/p>\n<p>Como en toda posada no pod\u00eda faltar la pi\u00f1ata y no fue una sino varias las que rompieron, esparciendo dulces y alegr\u00edas, adem\u00e1s el Gobernador llev\u00f3 cientos de pizzas que reparti\u00f3 junto a su esposa a las y los all\u00ed presentes.<\/p>\n<p>Un momento por dem\u00e1s emotivo fue cuando Ruth Gonz\u00e1lez Silva comenz\u00f3 a entregar los juguetes a los hijos de las PPL, iluminando a\u00fan m\u00e1s las caritas de ni\u00f1as y ni\u00f1os que ans\u00edan el regreso a casa de sus padres y madres.<\/p>\n<p>El momento estelar fue cuando la banda de rock El Gran Silencio reverber\u00f3 en los grises muros del penal y puso a cantar y bailar a las PPL y sus familias, con canciones como. \u201cDormir So\u00f1ando\u201d, \u201cChuntaro Style\u201d y \u201cMitote\u201d, entre muchas otras.<\/p>\n<p>\u00c9ste es el Gobierno del cambio, el Gobierno humano que impulsa los anhelos de las y los potosinos y el que tiende la mano a quienes merecen otra oportunidad.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 La banda de rock \u201cEl Gran Silencio\u201d puso a bailar y cantar a personas en el Centro de Reinserci\u00f3n Social y a sus familias. Acompa\u00f1ado por la Presidenta del Sistema Estatal para el Desarrollo Integral de la Familia Ruth Gonz\u00e1lez Silva entregan juguetes, dulces, &hellip; <\/p>\n","protected":false},"author":1,"featured_media":62897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[],"class_list":["post-62896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=62896"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62896\/revisions"}],"predecessor-version":[{"id":62898,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62896\/revisions\/62898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/62897"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=62896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=62896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=62896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}