{"id":62902,"date":"2021-12-19T21:39:30","date_gmt":"2021-12-20T03:39:30","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=62902"},"modified":"2021-12-19T21:39:30","modified_gmt":"2021-12-20T03:39:30","slug":"ricardo-gallardo-se-suma-a-exigencia-de-gobernadores-de-la-4t-a-favor-de-consulta-de-revocacion-de-mandato","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/ricardo-gallardo-se-suma-a-exigencia-de-gobernadores-de-la-4t-a-favor-de-consulta-de-revocacion-de-mandato\/","title":{"rendered":"Ricardo Gallardo se suma a exigencia de gobernadores de la 4t a favor de consulta de revocaci\u00f3n de mandato"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>Le exigen al Instituto Nacional Electoral reconsidere decisi\u00f3n de aplazar la fecha de la consulta<\/strong><\/li>\n<li><strong>El Gobernante potosino suscribe desplegado en defensa de los derechos pol\u00edticos<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>El Mandatario de San Luis Potos\u00ed Ricardo Gallardo Cardona se sum\u00f3 a las y los Gobernadores de la Cuarta Transformaci\u00f3n que exigen al Instituto Nacional Electoral (INE) la realizaci\u00f3n de la revocaci\u00f3n de mandato que plante\u00f3 el Presidente Andr\u00e9s Manuel L\u00f3pez Obrador y est\u00e1 consagrada en la Constituci\u00f3n federal.<\/p>\n<p>El libre ejercicio de los derechos de las y los mexicanos no se puede ver impedido por la decisi\u00f3n del Consejo General del INE, tambi\u00e9n violenta la resoluci\u00f3n de la Suprema Corte de Justicia de la Naci\u00f3n.<\/p>\n<p>Con el argumento de que no hay recursos suficientes, el presidente del INE Lorenzo C\u00f3rdova, y con el apoyo de otros Consejeros, pretende aplazar la fecha de la consulta para la revocaci\u00f3n del mandato presidencial.<\/p>\n<p>El Gobernante potosino suscribi\u00f3 el desplegado en el que aparecen las y los Gobernadores de la 4T, en el que se considera que \u201cla lucha por la democracia participativa tiene muchos a\u00f1os y tiene implicaciones que van m\u00e1s all\u00e1 de quienes hoy ostentamos un cargo p\u00fablico, lo que est\u00e1 en juego no es el resultado de una consulta en espec\u00edfico, lo que est\u00e1 en juego es si las mexicanas y mexicanos tenemos derecho a ser tomados en cuenta para las decisiones trascendentales de nuestra patria\u201d.<\/p>\n<p>\u201cLa democracia no es un proceso que se vive cada seis a\u00f1os, debe ser un sistema en donde todos los d\u00edas el pueblo ejerce sus derechos de participaci\u00f3n y decisi\u00f3n\u201d, se agrega en el desplegado y adem\u00e1s se solicita a las y los Consejeros del INE a que reconsideren su decisi\u00f3n, \u201ccon una perspectiva garantista en favor de la democracia participativa y de un compromiso con el pueblo y la democracia\u201d.<\/p>\n<p>El desplegado lo suscriben las Gobernadoras Marina del Pilar \u00c1vila (Baja California), Layda Sansores (Campeche), Indira Vizcaino Silva (Colima), Evelyn Salgado (Guerrero), Lorena Cu\u00e9llar (Tlaxcala) y la Jefa de Gobierno de la Ciudad M\u00e9xico Claudia Sheinbaum; y los Gobernadores David Monreal (Zacatecas), Ricardo Gallardo Cardona (San Luis Potos\u00ed), Alfonso Durazo (Sonora), Carlos Manuel Merino (Tabasco), Alfredo Ram\u00edrez Bedolla (Michoac\u00e1n), Miguel \u00c1ngel Navarro (Nayarit), entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Le exigen al Instituto Nacional Electoral reconsidere decisi\u00f3n de aplazar la fecha de la consulta El Gobernante potosino suscribe desplegado en defensa de los derechos pol\u00edticos &nbsp; El Mandatario de San Luis Potos\u00ed Ricardo Gallardo Cardona se sum\u00f3 a las y los Gobernadores de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":62903,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[],"class_list":["post-62902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=62902"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62902\/revisions"}],"predecessor-version":[{"id":62904,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/62902\/revisions\/62904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/62903"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=62902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=62902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=62902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}