{"id":67306,"date":"2022-03-25T07:46:01","date_gmt":"2022-03-25T13:46:01","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=67306"},"modified":"2022-03-25T07:46:01","modified_gmt":"2022-03-25T13:46:01","slug":"cabildo-aprueba-enviar-al-congreso-local-iniciativa-para-regular-la-quema-de-polvora","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/cabildo-aprueba-enviar-al-congreso-local-iniciativa-para-regular-la-quema-de-polvora\/","title":{"rendered":"Cabildo aprueba enviar al Congreso Local iniciativa para regular la quema de p\u00f3lvora"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ciudad Valles, SLP.- Durante la D\u00e9cima Sesi\u00f3n Extraordinaria de Cabildo realizada en el sal\u00f3n Rafael Curiel Gallegos, fue aprobada por mayor\u00eda, enviar al Congreso del Estado la iniciativa para que en Ciudad Valles se regule el uso de pirotecnia, con el objetivo dejar de utilizar la p\u00f3lvora en celebraciones, ferias o en alguna otra actividad festiva.<\/p>\n<p>Dicha propuesta fue hecha por el alcalde David Armando Medina Salazar, con la finalidad de que se regule la autorizaci\u00f3n de permisos para la quema de p\u00f3lvora, y con ello proteger a las personas con espectro autista, u otros padecimientos, e incluso, evitar que las mascotas sufran al hacer explotar la pirotecnia, donde tambi\u00e9n se invita al resto del estado a sumarse a esta iniciativa.<\/p>\n<p>De igual manera, fue aprobado por mayor\u00eda el otorgar un apoyo econ\u00f3mico bimestral a los 30 integrantes de la Banda de Guerra Municipal, como una compensaci\u00f3n por la labor que realizan en eventos importantes del municipio, siendo la cantidad de<br \/>\nmil pesos cada dos meses la que estar\u00e1n recibiendo.<\/p>\n<p>Asimismo, tambi\u00e9n fue aprobada por mayor\u00eda la propuesta del alcalde de otorgar atenci\u00f3n m\u00e9dica de primer nivel a los miembros del H. Cuerpo de Bomberos cuando en el ejercicio de sus funciones sea requerido.<\/p>\n<p>Otra de las propuestas del edil fue turnada a la Comisi\u00f3n para su an\u00e1lisis, se trata de la propuesta que tiene como fin el autorizar a la Tesorera municipal la apertura de una cuenta bancaria para la creaci\u00f3n de un fondo destinado a apoyar a las v\u00edctimas de desastres naturales y de esta manera, contar con recursos para asistir a las familias que hayan sufrido alg\u00fan percance por incendios, inundaciones u otro fen\u00f3meno natural .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ciudad Valles, SLP.- Durante la D\u00e9cima Sesi\u00f3n Extraordinaria de Cabildo realizada en el sal\u00f3n Rafael Curiel Gallegos, fue aprobada por mayor\u00eda, enviar al Congreso del Estado la iniciativa para que en Ciudad Valles se regule el uso de pirotecnia, con el objetivo dejar de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":67307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,4],"tags":[],"class_list":["post-67306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/67306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=67306"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/67306\/revisions"}],"predecessor-version":[{"id":67308,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/67306\/revisions\/67308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/67307"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=67306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=67306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=67306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}