{"id":73412,"date":"2022-09-10T09:47:50","date_gmt":"2022-09-10T15:47:50","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=73412"},"modified":"2022-09-10T09:47:50","modified_gmt":"2022-09-10T15:47:50","slug":"secretario-de-seguridad-estatal-llama-a-construir-una-gran-alianza-por-la-seguridad-publica","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/secretario-de-seguridad-estatal-llama-a-construir-una-gran-alianza-por-la-seguridad-publica\/","title":{"rendered":"Secretario de Seguridad Estatal llama a construir una gran Alianza por la Seguridad P\u00fablica"},"content":{"rendered":"<div class=\"\" dir=\"auto\">\n<div id=\"jsc_c_rm\" class=\"d2hqwtrz r227ecj6 ez8dtbzv gt60zsk1\" data-ad-comet-preview=\"message\" data-ad-preview=\"message\">\n<div class=\"alzwoclg cqf1kptm siwo0mpr gu5uzgus\">\n<div class=\"jroqu855 nthtkgg5\">\n<div class=\"m8h3af8h l7ghb35v kjdc1dyq kmwttqpk gh25dzvf n3t5jt4f\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"l7ghb35v kjdc1dyq kmwttqpk gh25dzvf jikcssrz n3t5jt4f\">\n<div dir=\"auto\">Encabeza reuni\u00f3n de trabajo con 12 alcaldes y alcaldesas de la zona Media y titulares de Seguridad P\u00fablica Municipal, para continuar y fortalecer programas y proyectos dentro del Plan Integral de Seguridad.<\/div>\n<\/div>\n<div class=\"l7ghb35v kjdc1dyq kmwttqpk gh25dzvf jikcssrz n3t5jt4f\">\n<div dir=\"auto\">En el municipio de Rioverde, el Secretario de Seguridad y Protecci\u00f3n Ciudadana del Estado, General Guzmar \u00c1ngel Gonz\u00e1lez Castillo hizo un en\u00e9rgico llamado a las alcaldesas y alcaldes de la zona Media para que dentro de sus planes y proyectos de gobierno apuesten a la prevenci\u00f3n de los delitos, como una estrategia clave para que sus habitantes se sientan m\u00e1s seguros y se les brinde protecci\u00f3n a su bienestar, y de esta manera ir acorde al Plan Integral de Seguridad que promueve el Gobernador del Estado, Ricardo Gallardo Cardona.<\/div>\n<\/div>\n<div class=\"l7ghb35v kjdc1dyq kmwttqpk gh25dzvf jikcssrz n3t5jt4f\">\n<div dir=\"auto\">Al encabezar una reuni\u00f3n de trabajo con autoridades municipales de esta regi\u00f3n, pidi\u00f3 a los hombres y mujeres responsables de dirigir los destinos de sus demarcaciones a seguir sumando esfuerzos, luego de estar pr\u00f3ximos a cumplir un a\u00f1o de gesti\u00f3n: \u201csigamos actuando con mucha responsabilidad y juntos impulsemos una gran alianza por la seguridad p\u00fablica, las condiciones actuales as\u00ed lo demandan\u201d.<\/div>\n<\/div>\n<div class=\"l7ghb35v kjdc1dyq kmwttqpk gh25dzvf jikcssrz n3t5jt4f\">\n<div dir=\"auto\">En dicho evento celebrado en el Instituto Municipal de Arte y Cultura de Rioverde, se ofreci\u00f3 un panorama actual sobre las condiciones que guardan las polic\u00edas municipales de esta regi\u00f3n, subrayando la necesidad de fortalecer en todos los sentidos a las corporaciones que siguen adoleciendo de la falta de capacitaci\u00f3n, profesionalizaci\u00f3n y actualizaci\u00f3n de todos sus elementos, \u201cde ah\u00ed que constantemente estemos pidiendo a las y los alcaldes que le inviertan en la certificaci\u00f3n de sus oficiales\u201d.<\/div>\n<\/div>\n<div class=\"l7ghb35v kjdc1dyq kmwttqpk gh25dzvf jikcssrz n3t5jt4f\">\n<div dir=\"auto\">Sostuvo enf\u00e1tico que por parte de la Secretar\u00eda de Seguridad Estatal se les ofrecen todas las facilidades para que su estado de fuerza municipal participe en los programas permanentes de capacitaci\u00f3n brindados a trav\u00e9s de la Academia Estatal de Polic\u00eda, para que con ello tengan polic\u00edas certificados y confiables. Otro de los aspectos abordados fue lo relacionado con la licencia colectiva para la portaci\u00f3n de armas de fuego por parte de los agentes municipales, aunado al compromiso signado por 34 municipios para la adquisici\u00f3n de armamento.<\/div>\n<\/div>\n<div class=\"l7ghb35v kjdc1dyq kmwttqpk gh25dzvf jikcssrz n3t5jt4f\">\n<div dir=\"auto\">Gonz\u00e1lez Castillo agradeci\u00f3 la presencia y el inter\u00e9s de las y los ediles participantes y dijo que con ello se genera una sinergia muy importante dando seguimiento a las pol\u00edticas de seguridad p\u00fablica, \u201cestaremos atentos para apoyarlos en lo que necesiten\u201d.<\/div>\n<\/div>\n<div class=\"l7ghb35v kjdc1dyq kmwttqpk gh25dzvf jikcssrz n3t5jt4f\">\n<div dir=\"auto\">Asistieron a esta reuni\u00f3n, las y los presidentes municipales Florisela Hern\u00e1ndez Ch\u00e1vez de Alaquines; Jorge Omar Mu\u00f1\u00f3z Mart\u00ednez de C\u00e1rdenas; Mireya Vancini Villanueva de Ciudad del Ma\u00edz; Marco Antonio Gonz\u00e1lez Jasso de Ciudad Fern\u00e1ndez; Mar\u00eda Leticia V\u00e1zquez Hern\u00e1ndez de Cerritos; Sergio Alberto Izaguirre Ponce de Lagunillas; Pablo Berrones Alvarado de Ray\u00f3n; Arnulfo Urbiola Rom\u00e1n de Rioverde; Luis Carlos Pereyra Govea de San Ciro de Acosta; Arturo El\u00edas Rodr\u00edguez de San Nicol\u00e1s Tolentino; Mar\u00eda del Amparo Charles Landaverde de Santa Catarina y Lisa Abigail Izaguirre de Villa Ju\u00e1rez.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"jsc_c_rn\" class=\"om3e55n1\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Encabeza reuni\u00f3n de trabajo con 12 alcaldes y alcaldesas de la zona Media y titulares de Seguridad P\u00fablica Municipal, para continuar y fortalecer programas y proyectos dentro del Plan Integral de Seguridad. En el municipio de Rioverde, el Secretario de Seguridad y Protecci\u00f3n Ciudadana del &hellip; <\/p>\n","protected":false},"author":1,"featured_media":73413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4],"tags":[],"class_list":["post-73412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/73412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=73412"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/73412\/revisions"}],"predecessor-version":[{"id":73414,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/73412\/revisions\/73414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/73413"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=73412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=73412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=73412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}