{"id":737,"date":"2011-08-01T18:35:59","date_gmt":"2011-08-02T00:35:59","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/2011\/08\/01\/no-hay-un-plan-de-desarrollo-para-la-ganaderia\/"},"modified":"2011-08-01T18:35:59","modified_gmt":"2011-08-02T00:35:59","slug":"no-hay-un-plan-de-desarrollo-para-la-ganaderia","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/no-hay-un-plan-de-desarrollo-para-la-ganaderia\/","title":{"rendered":"NO HAY UN PLAN DE DESARROLLO PARA LA GANADERIA"},"content":{"rendered":"<div align=\"justify\"><strong>-\u201cY las soluciones de fondo\u201d<\/strong><br \/>Dirigentes de las Asociaciones Ganaderas Locales de la Huasteca Potosina, pidieron al Secretario de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, H\u00e9ctor Rodr\u00edguez Castro, no dar \u201cmejoralitos\u201d y presente un\u00a0 Plan de Desarrollo para la actividad ganadera.<br \/>Encabezados por \u00c1ngel de la Vega, presidente de la Uni\u00f3n Ganadera Regional, Porfirio Alejandro S\u00e1nchez, de la Asociaci\u00f3n de Ciudad Valles, Jos\u00e9 Luis Ramiro Galero de la Asociaci\u00f3n de Tamuin entre otros dirigentes ganaderos, el titular de SEDARH, escucho la problem\u00e1tica del sector ganadero, donde destac\u00f3 el reclamo de los productores por la falta de un Plan de Desarrollo para la Ganader\u00eda en el Estado.<br \/>Le manifestaron su molestia de c\u00f3mo se manejo el programa\u00a0 seguro catastr\u00f3fico del Gobierno Federal, porque es solo un \u201cmejoradito\u201d a la realidad de la actividad ganadera, ya que es un est\u00edmulo a los productores afectados por la sequ\u00eda y las inundaciones el cual aun no se entrega y se les aviso muy tarde a las asociaciones ganaderas.<br \/>Apenas en esta reuni\u00f3n con ganaderos, Rodr\u00edguez Castro, se comprometi\u00f3 a entregar la lista de requisitos que se deben de cumplir para acceder no solo a ese programa si no a otros que maneja SEDARH-SAGARPA pero no se hab\u00edan difundido.<br \/>Por otra parte, los dirigentes ganaderos preocupados por la situaci\u00f3n por la que atraviesa la actividad ganadera en la huasteca, preguntaron al Secretario de Desarrollo Agropecuario, \u00bfCu\u00e1l es el Plan de Desarrollo para la Ganader\u00eda?, ya que cada vez hay menos ganado en los potreros, el precio es controlado por grandes empresarios, hay menos apoyos para el desarrollo de la actividad ganadera, y para el colmo se suspendi\u00f3 el programa de repoblaci\u00f3n de hatos ganaderos por mal manejos de los recursos federales, lo cual deja vulnerables a los productores.<br \/>Puntualizaron, que se vive una real \u201ccrisis econ\u00f3mica\u201d en el sector ganadero, al grado de que diariamente se despide a un importante n\u00famero de trabajadores agropecuarios que solo incrementan los \u00edndices de desempleo.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>-\u201cY las soluciones de fondo\u201dDirigentes de las Asociaciones Ganaderas Locales de la Huasteca Potosina, pidieron al Secretario de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos, H\u00e9ctor Rodr\u00edguez Castro, no dar \u201cmejoralitos\u201d y presente un\u00a0 Plan de Desarrollo para la actividad ganadera.Encabezados por \u00c1ngel de la Vega, presidente &hellip; <\/p>\n","protected":false},"author":1,"featured_media":736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ganaderos"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=737"}],"version-history":[{"count":0,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/736"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}