{"id":75706,"date":"2022-11-09T06:25:35","date_gmt":"2022-11-09T12:25:35","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=75706"},"modified":"2022-11-09T06:25:35","modified_gmt":"2022-11-09T12:25:35","slug":"guardia-civil-rescata-a-mas-de-100-migrantes-en-la-zona-metropolitana-de-san-luis-potosi","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/guardia-civil-rescata-a-mas-de-100-migrantes-en-la-zona-metropolitana-de-san-luis-potosi\/","title":{"rendered":"Guardia Civil rescata a m\u00e1s de 100 migrantes en la zona metropolitana de San Luis Potos\u00ed"},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Guardia Civil Estatal brinda apoyo al Instituto Nacional de Migraci\u00f3n<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana del Estado, informa que este martes a trav\u00e9s de distintas incursiones operativas a cargo de la Guardia Civil Estatal y el Instituto Nacional de Migraci\u00f3n, se logr\u00f3 la localizaci\u00f3n y rescate de m\u00e1s de 100 personas entre adultos y menores de edad de diversas nacionalidades quienes se encontraban retenidos en dos hoteles de la ciudad y la zona conurbada.<\/p>\n<p>Derivado de la colaboraci\u00f3n interinstitucional que existe con el INM se acude a brindar apoyo mediante labores de seguridad y resguardo primeramente en el \u201cHotel California\u201d de la carretera a Rioverde en el Municipio de Soledad, ah\u00ed se rescataron a 59 personas de nacionalidad cubana, guatemalteca, hondure\u00f1a y ecuatoriana.<\/p>\n<p>Posteriormente se activ\u00f3 una solicitud de apoyo en el negocio con raz\u00f3n social \u201cHotel Espa\u00f1a\u201d situado en Avenida Universidad en la capital potosina confirmando que en su interior hab\u00eda hombres y mujeres y menores de origen cubano, mismos que no pudieron acreditar su estancia legal en el pa\u00eds, adem\u00e1s de se\u00f1alar que fueron abandonados.<\/p>\n<p>Dichos operativos de llevaron a cabo bajo protocolos de estricto respeto a los derechos humanos de las personas que cabe hacer menci\u00f3n no mostraron afectaciones mayores de salud.<\/p>\n<p>Ser\u00e1 el personal del Instituto Nacional de Migraci\u00f3n quienes se hagan cargo de los tr\u00e1mites correspondientes para su repatriaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 &nbsp; Guardia Civil Estatal brinda apoyo al Instituto Nacional de Migraci\u00f3n &nbsp; La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana del Estado, informa que este martes a trav\u00e9s de distintas incursiones operativas a cargo de la Guardia Civil Estatal y el Instituto Nacional de Migraci\u00f3n, &hellip; <\/p>\n","protected":false},"author":1,"featured_media":75709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,12,5],"tags":[],"class_list":["post-75706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-nacional","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/75706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=75706"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/75706\/revisions"}],"predecessor-version":[{"id":75710,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/75706\/revisions\/75710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/75709"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=75706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=75706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=75706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}