{"id":80375,"date":"2023-02-20T17:18:48","date_gmt":"2023-02-20T23:18:48","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=80375"},"modified":"2023-02-20T17:18:48","modified_gmt":"2023-02-20T23:18:48","slug":"anuncia-sege-segunda-edicion-estatal-de-la-feria-de-universidades-interactiva","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/anuncia-sege-segunda-edicion-estatal-de-la-feria-de-universidades-interactiva\/","title":{"rendered":"Anuncia SEGE segunda edici\u00f3n estatal de la Feria de Universidades Interactiva"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>\u2022 Estas actividades forman parte de la estrategia del Gobierno del cambio para asegurar que las y los j\u00f3venes contin\u00faen sus estudios universitarios, la SEGE coordina la Funi 2023<\/p>\n<p>Como parte de la estrategia emprendida por el Gobierno del cambio que encabeza Ricardo Gallardo Cardona, para garantizar que ning\u00fan joven se quede sin estudios universitarios, este a\u00f1o se realizar\u00e1 la segunda edici\u00f3n Estatal de la \u201cFeria de Universidades Interactiva (Funi) 2023\u201d, que concentra la m\u00e1xima oferta educativa en los niveles medio superior, carreras t\u00e9cnicas, profesional, de estudios de posgrado, maestr\u00edas y doctorados, con la participaci\u00f3n de 90 instituciones, los d\u00edas 3 y 4 de marzo en el pabell\u00f3n tres de la Feria Nacional Potosina (Fenapo).<br \/>\nEl titular de la Secretar\u00eda de Educaci\u00f3n de Gobierno del Estado (SEGE), Juan Carlos Torres Cedillo, detall\u00f3 que, este es un esfuerzo que ha realizado el Gobierno del cambio para ofrecer las distintas opciones de estudios al que pueden acceder las y los j\u00f3venes potosinos, en escuelas tanto p\u00fablicas como privadas, donde se les ofrecen becas. \u201cEs una estrategia que fortalece la educaci\u00f3n y fomenta la profesionalizaci\u00f3n ante el crecimiento y desarrollo econ\u00f3mico que mantiene el Estado\u201d.<br \/>\nEn esta segunda edici\u00f3n Estatal se espera la afluencia de cinco mil estudiantes durante los d\u00edas viernes 3 de marzo en un horario de 8:00 a 18:00 horas y s\u00e1bado 4 de marzo de 8:00 a 14:00 horas en el pabell\u00f3n tres de la Feria Nacional Potosina (Fenapo), lugar que cuenta con la infraestructura necesaria para llevar con \u00e9xito este magno evento, que se ha posicionado como una de las exposiciones de oferta acad\u00e9mica m\u00e1s grande de la zona baj\u00edo.<br \/>\n\u201cLa invitaci\u00f3n es para que, las y los estudiantes vengan con sus amigos, hermanos, compa\u00f1eros de clase y sus madres y padres para que, en unidad, puedan tomar decisiones sobre su futuro, las instituciones acuden con material did\u00e1ctico, ofertas de estudios y demostraciones sobre las carreras y sus planes de estudio, para que puedan tomar la mejor decisi\u00f3n\u201d, finaliz\u00f3 el titular de la dependencia Torres Cedillo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u2022 Estas actividades forman parte de la estrategia del Gobierno del cambio para asegurar que las y los j\u00f3venes contin\u00faen sus estudios universitarios, la SEGE coordina la Funi 2023 Como parte de la estrategia emprendida por el Gobierno del cambio que encabeza Ricardo Gallardo &hellip; <\/p>\n","protected":false},"author":1,"featured_media":80376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,5],"tags":[],"class_list":["post-80375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=80375"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80375\/revisions"}],"predecessor-version":[{"id":80377,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80375\/revisions\/80377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/80376"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=80375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=80375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=80375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}