{"id":80496,"date":"2023-02-23T06:32:11","date_gmt":"2023-02-23T12:32:11","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=80496"},"modified":"2023-02-23T06:32:11","modified_gmt":"2023-02-23T12:32:11","slug":"slp-ya-es-de-primer-nivel-con-obras-del-gobernador-ricardo-gallardo-reconocen-beneficiarios","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/slp-ya-es-de-primer-nivel-con-obras-del-gobernador-ricardo-gallardo-reconocen-beneficiarios\/","title":{"rendered":"SLP ya es de primer nivel con obras del gobernador Ricardo Gallardo, reconocen beneficiarios"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>Las acciones del Gobierno del cambio hacen una ciudad y Estado id\u00f3neo para invertir, radicar y crecer, con beneficios para todas y todos, coincidieron habitantes y usuarios de la renovada avenida Industrias <\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Con las obras de infraestructura y la atracci\u00f3n de nuevas grandes empresas que generan m\u00e1s empleos y mejor pagados, el Gobernador Ricardo Gallardo Cardona ha hecho de San Luis Potos\u00ed un Estado de primer nivel, un lugar id\u00f3neo para invertir, radicar y crecer, con beneficios para todas y todos, coincidieron potosinas y potosinos beneficiarios por la modernizaci\u00f3n de la avenida Industrias en su primera etapa desde Circuito Potos\u00ed Oriente al Eje 124.<\/p>\n<p>\u201cGracias a su vocaci\u00f3n de servicio sin distinci\u00f3n, ya se nota el cambio para la entidad desde que entr\u00f3 como Gobernador\u201d, asegur\u00f3 Cirilo Montoya, vecino de la colonia San Miguel, quien agradeci\u00f3 al Mandatario Estatal por este tipo de acciones.<\/p>\n<p>La ciudadana Hilda Benavides, vecina del eje 104, dijo: \u201cahora hay mayor seguridad, pues la avenida est\u00e1 ya iluminada, hay sem\u00e1foros que van a evitar accidentes y atropellados, no como antes\u201d, destac\u00f3 que antes ninguna administraci\u00f3n estatal anterior los hab\u00eda atendido.<\/p>\n<p>Por su parte, Generosa Torres, habitante por d\u00e9cadas de la colonia Industrial San Luis, destac\u00f3 que el Gobernador Gallardo Cardona es, \u201cun joven muy trabajador, como ninguno otro, y permite un despegue al progreso y al futuro\u201d.<\/p>\n<p>Finalmente, Paula Salazar y Sof\u00eda Reyes, vecinas del Eje 102, comentaron que ahora se podr\u00e1 abatir la delincuencia, \u201ces maravilloso el cambio que estamos observando\u201d, comentaron tras externar su deseo de que San Luis Potos\u00ed contin\u00fae con Gallardo Cardona, por sus obras y acciones, por la senda del progreso en favor de todas y todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Las acciones del Gobierno del cambio hacen una ciudad y Estado id\u00f3neo para invertir, radicar y crecer, con beneficios para todas y todos, coincidieron habitantes y usuarios de la renovada avenida Industrias &nbsp; Con las obras de infraestructura y la atracci\u00f3n de nuevas grandes &hellip; <\/p>\n","protected":false},"author":1,"featured_media":80497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,5],"tags":[],"class_list":["post-80496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=80496"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80496\/revisions"}],"predecessor-version":[{"id":80498,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80496\/revisions\/80498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/80497"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=80496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=80496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=80496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}