{"id":80505,"date":"2023-02-23T06:36:39","date_gmt":"2023-02-23T12:36:39","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=80505"},"modified":"2023-02-23T06:36:39","modified_gmt":"2023-02-23T12:36:39","slug":"estrategia-de-grupo-de-ayuda-mutua-aporta-al-control-y-tratamiento-de-enfermedades-cronicas","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/estrategia-de-grupo-de-ayuda-mutua-aporta-al-control-y-tratamiento-de-enfermedades-cronicas\/","title":{"rendered":"Estrategia de grupo de ayuda mutua aporta al control y tratamiento de enfermedades cr\u00f3nicas  \u00a0"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>SLP cerr\u00f3 el 2022 con 20 Grupos de Ayuda Mutua de Enfermedades Cr\u00f3nicas los cuales benefician a alrededor de 400 usuarios.<\/strong><\/li>\n<li><strong>Con el apoyo del personal de salud, en los grupos GAM EC se tiene como objetivo coadyuvar al control metab\u00f3lico de enfermedades cr\u00f3nicas no transmisibles, el autocuidado y autoestima.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Un grupo de ayuda mutua de enfermedades cr\u00f3nicas (GAM EC) se define como la organizaci\u00f3n de los pacientes que con el apoyo del personal de salud, tiene el objetivo de coadyuvar al control metab\u00f3lico de sus enfermedades cr\u00f3nicas no transmisibles, a trav\u00e9s de estrategias educativas que promuevan la adopci\u00f3n de un estilo de vida saludable. Actualmente en el estado se tiene un censo de 20 grupos GAM EC, que benefician alrededor de 400 usuarios.<\/p>\n<p>&nbsp;<\/p>\n<p>El Maestro en Salud P\u00fablica Adolfo V\u00e9liz Silva, Jefe del Departamento de Atenci\u00f3n del Adulto y Adulto Mayor de los Servicios de Salud de Gobierno del Estado, mencion\u00f3 que a trav\u00e9s del personal de las unidades de Salud se ponen en pr\u00e1ctica acciones como el impartir sesiones educativas, sesiones de actividad f\u00edsica, consultas m\u00e9dicas y monitoreo. El programa GAM EC beneficia al cien por ciento de las personas con enfermedades cr\u00f3nicas al darles el conocimiento sobre su enfermedad.<\/p>\n<p>&nbsp;<\/p>\n<p>Agreg\u00f3 que la estrategia de trabajo de los grupos de ayuda mutua de enfermedades cr\u00f3nicas, ha demostrado su efectividad a trav\u00e9s del aprendizaje y apoyo mutuo sin detrimento de los protocolos de tratamiento m\u00e9dico, lo cual se considera una forma eficaz de crear ambientes favorables para la salud. Benefician el desarrollo y mejoran las condiciones personales y sociales de los que participan en ellos, elevando significativamente la autoestima y potencializando el autocuidado para influir de manera positiva en la protecci\u00f3n de la salud y prevenci\u00f3n de las enfermedades.<\/p>\n<p>&nbsp;<\/p>\n<p>Participan tanto las personas que padecen directamente los problemas de salud como los familiares y amigos quienes lo enfrentan de forma indirecta, donde encuentran un espacio de contenci\u00f3n emocional de conocimiento e informaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Finalmente, V\u00e9liz Silva, destac\u00f3 que la atenci\u00f3n y educaci\u00f3n a la salud no comienzan ni acaban en las unidades m\u00e9dicas, se extiende a espacios fuera del consultorio m\u00e9dico y se prolongan a trav\u00e9s del autocuidado y la ayuda mutua entre iguales, lo cual constituye todo un potencial de promoci\u00f3n de la salud en la sociedad m\u00e1s necesitada a la cual es preciso apoyar e incentivar. Para la poblaci\u00f3n interesada en formar parte de un grupo, s\u00f3lo necesita acercarse al centro de salud m\u00e1s cercano para brindarle mayor informaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; SLP cerr\u00f3 el 2022 con 20 Grupos de Ayuda Mutua de Enfermedades Cr\u00f3nicas los cuales benefician a alrededor de 400 usuarios. Con el apoyo del personal de salud, en los grupos GAM EC se tiene como objetivo coadyuvar al control metab\u00f3lico de enfermedades cr\u00f3nicas &hellip; <\/p>\n","protected":false},"author":1,"featured_media":80506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4],"tags":[],"class_list":["post-80505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=80505"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80505\/revisions"}],"predecessor-version":[{"id":80507,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80505\/revisions\/80507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/80506"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=80505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=80505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=80505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}