{"id":80893,"date":"2023-03-04T07:58:23","date_gmt":"2023-03-04T13:58:23","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=80893"},"modified":"2023-03-05T07:59:08","modified_gmt":"2023-03-05T13:59:08","slug":"programa-anual-de-capacitacion-2023-refuerza-habilidades-de-las-y-los-servidores-publicos","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/programa-anual-de-capacitacion-2023-refuerza-habilidades-de-las-y-los-servidores-publicos\/","title":{"rendered":"Programa anual de capacitaci\u00f3n 2023 refuerza habilidades de las y los servidores p\u00fablicos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>Oficial\u00eda Mayor, ofrece a personal del Centro de Convenciones, curso \u201cAtenci\u00f3n en el Servicio\u201d <\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>El Programa Anual de Capacitaci\u00f3n 2023, que el Gobierno del cambio encabezado por Ricardo Gallardo Cardona implementa, responde a las necesidades para mejorar la actitud, conocimiento, habilidades y conductas de las y los servidores p\u00fablicos, afirm\u00f3 el oficial mayor, No\u00e9 Lara Enr\u00edquez, quien agreg\u00f3 que se reforzar\u00e1 la actividad enfocada en aportar un conocimiento que permita que el capital humano realice un mejor trabajo en beneficio de la sociedad potosina.<\/p>\n<p>Bajo esta din\u00e1mica, la Oficial\u00eda Mayor, trabaja de manera coordinada con todas las dependencias donde se da respuesta a las demandas solicitadas, como en el caso del Centro de Convenciones, que solicit\u00f3 el curso presencial \u00abAtenci\u00f3n en el Servicio\u00bb impartido por Edson Enrique Zaragoza Vera a 19 personas servidoras p\u00fablicas.<\/p>\n<p>De acuerdo a la tem\u00e1tica de la capacitaci\u00f3n se analizaron los temas: Factores estrat\u00e9gicos en la atenci\u00f3n a la ciudadan\u00eda; La comunicaci\u00f3n efectiva; T\u00e9cnicas de gesti\u00f3n de las emociones; El trabajo en equipo para atender con calidad a la ciudadan\u00eda; Est\u00e1ndar de competencia 105: Atenci\u00f3n al ciudadano en el sector p\u00fablico.<\/p>\n<p>El objetivo general de este curso fue que las y los participantes apliquen los requerimientos establecidos en el est\u00e1ndar de competencia mediante t\u00e9cnicas demostrativas y de di\u00e1logo, discusi\u00f3n para atender con eficiencia, eficacia y calidez a la ciudadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Oficial\u00eda Mayor, ofrece a personal del Centro de Convenciones, curso \u201cAtenci\u00f3n en el Servicio\u201d &nbsp; El Programa Anual de Capacitaci\u00f3n 2023, que el Gobierno del cambio encabezado por Ricardo Gallardo Cardona implementa, responde a las necesidades para mejorar la actitud, conocimiento, habilidades y conductas &hellip; <\/p>\n","protected":false},"author":1,"featured_media":80894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4],"tags":[],"class_list":["post-80893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=80893"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80893\/revisions"}],"predecessor-version":[{"id":80895,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/80893\/revisions\/80895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/80894"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=80893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=80893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=80893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}