{"id":81558,"date":"2023-03-21T08:19:54","date_gmt":"2023-03-21T14:19:54","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=81558"},"modified":"2023-03-21T08:19:54","modified_gmt":"2023-03-21T14:19:54","slug":"coordinara-gobierno-del-cambio-programas-nacionales-de-planeacion-urbana-y-ordenamiento-territorial","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/coordinara-gobierno-del-cambio-programas-nacionales-de-planeacion-urbana-y-ordenamiento-territorial\/","title":{"rendered":"Coordinar\u00e1 gobierno del cambio, programas nacionales de planeaci\u00f3n urbana y ordenamiento territorial"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><b><\/b><strong><b>Despu\u00e9s de m\u00e1s de 30 a\u00f1os se estar\u00e1n coordinando acciones a nivel nacional, impulsando el crecimiento social, econ\u00f3mico y urbano<\/b><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>En continuidad a las pol\u00edticas p\u00fablicas del Gobierno del cambio que dirige Ricardo Gallardo Cardona, la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras P\u00fablicas (Seduvop) con apoyo del Instituto Estatal de Planeaci\u00f3n Urbana (Ieplau), acudi\u00f3 a la firma de convenio con el Gobierno Federal, a trav\u00e9s de la Secretar\u00eda de Desarrollo Agrario, Territorial y Urbano (Sedatu), para la ejecuci\u00f3n del Programa de Fomento a la Planeaci\u00f3n Urbana, Metropolitana y Ordenamiento Territorial (PUMOT) y el Programa Metropolitano de Desarrollo Urbano, para seis municipios potosinos.<\/p>\n<p>En el PUMOT participan Ciudad Valles, Matehuala y Tamu\u00edn, y el objetivo de programa es fomentar el ordenamiento territorial y urbano de las entidades federativas, zonas metropolitanas, municipios y demarcaciones territoriales. Por otra parte, en la firma para el Convenio de la zona metropolitana, participan San Luis Potos\u00ed, Soledad de Graciano S\u00e1nchez y Villa de Reyes.<\/p>\n<p>De esta manera, la Seduvop a trav\u00e9s del Ieplau, coordinar\u00e1 los requerimientos que sean planteados por la Sedatu y su aplicaci\u00f3n en los municipios. Para el cumplimiento de las metas, se fortalecer\u00e1 el ordenamiento territorial y urbano del Estado, priorizando las necesidades locales. Se destaca el trabajo coordinado y la participaci\u00f3n en programas federales que desde hace m\u00e1s de 30 a\u00f1os no se llevaban a cabo.<\/p>\n<p>Adem\u00e1s, es importante la apertura, coordinaci\u00f3n e inter\u00e9s de los diferentes niveles de Gobierno, para lograr el adecuado crecimiento social, econ\u00f3mico y urbano, a trav\u00e9s de los instrumentos que den orden y establezcan el desarrollo de las ciudades potosinas a mediano y largo plazo.<\/p>\n<p>Los trabajos de elaboraci\u00f3n del PUMOT se publicar\u00e1n, una vez que sean concluidos, en el Peri\u00f3dico Oficial del Estado y posteriormente se registrar\u00e1 ante el Instituto Registral del Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Despu\u00e9s de m\u00e1s de 30 a\u00f1os se estar\u00e1n coordinando acciones a nivel nacional, impulsando el crecimiento social, econ\u00f3mico y urbano &nbsp; En continuidad a las pol\u00edticas p\u00fablicas del Gobierno del cambio que dirige Ricardo Gallardo Cardona, la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras &hellip; <\/p>\n","protected":false},"author":1,"featured_media":81559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4,12],"tags":[],"class_list":["post-81558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","category-inicio","category-nacional"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/81558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=81558"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/81558\/revisions"}],"predecessor-version":[{"id":81560,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/81558\/revisions\/81560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/81559"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=81558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=81558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=81558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}