{"id":81723,"date":"2023-03-25T08:09:23","date_gmt":"2023-03-25T14:09:23","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=81723"},"modified":"2023-03-27T08:10:16","modified_gmt":"2023-03-27T14:10:16","slug":"voluntad-y-trabajo-de-las-y-los-alcaldes-facilita-la-afronta-de-retos-en-seguridad-gobernador","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/voluntad-y-trabajo-de-las-y-los-alcaldes-facilita-la-afronta-de-retos-en-seguridad-gobernador\/","title":{"rendered":"Voluntad y trabajo de las y los alcaldes facilita la afronta de retos en seguridad: gobernador"},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>Por segunda vez, el Mandatario potosino Ricardo Gallardo Cardona dirige la Mesa de Coordinaci\u00f3n para la Construcci\u00f3n de la Paz en Venado <\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Venado, San Luis Potos\u00ed.- La puesta en marcha del Mando Policial Coordinado, recientemente formalizado con el respaldo de todas y todos los alcaldes, es una reafirmaci\u00f3n de la visi\u00f3n y la ocupaci\u00f3n que debe tener la seguridad p\u00fablica desde todos los \u00e1mbitos de Gobierno para devolver la paz y el orden a los 58 municipios, asever\u00f3 el Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona, al dirigir la Mesa de Coordinaci\u00f3n para la Construcci\u00f3n de la Paz en esta demarcaci\u00f3n, por segunda ocasi\u00f3n.<\/p>\n<p>Expres\u00f3 que nunca antes un Gobierno Estatal hab\u00eda logrado una sinergia tan integral en aras de proteger firmemente a las familias de las cuatro regiones, por lo que el compromiso, trabajo, voluntad y responsabilidad de las y los presidentes municipales habr\u00e1 de traer mayores y positivos resultados: \u201choy el Gobierno del cambio trabaja incansablemente por la seguridad de las y los potosinos, estamos avanzando con firmeza, los retos son fuertes, pero los afrontamos con valent\u00eda y en conjunto\u201d, agreg\u00f3.<\/p>\n<p>Con la presencia de la y los ediles de Charcas, Venado, Ahualulco y Moctezuma, acompa\u00f1ados de sus directores de seguridad p\u00fablica, el Jefe del Ejecutivo recalc\u00f3 que la ciudadan\u00eda merece tener polic\u00edas id\u00f3neos, capacitados, capaces de atender con vocaci\u00f3n sus llamados, con condiciones laborales y salarios dignos y justos, adscritos a la normativa legal, puesto que en m\u00faltiples ocasiones han sido detectados contraviniendo a la ley e incurriendo en posibles delitos.<\/p>\n<p>\u201cLas administraciones deben garantizar la contrataci\u00f3n correcta de sus polic\u00edas, proporcionarles la oportunidad de profesionalizarse e inducirlos mediante adiestramiento y conocimientos policiales hacia un buen desempe\u00f1o con la poblaci\u00f3n\u201d, manifest\u00f3 Gallardo Cardona, al tiempo de reconocer que la finalidad de las mesas estatales de seguridad es insistir en la regulaci\u00f3n de las corporaciones municipales, priorizando la coordinaci\u00f3n con la Guardia Civil Estatal, Guardia Nacional y Ej\u00e9rcito Mexicano.<\/p>\n<p>Por su parte, el titular de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana Estatal (SSPCE), Guzmar \u00c1ngel Gonz\u00e1lez Castillo, extern\u00f3 que a las y los alcaldes se les brinda todo el apoyo institucional de este Gobierno del cambio, para avanzar correctamente en el fortalecimiento de sus estados de fuerza y brindar verdadera defensa del patrimonio e integridad de sus habitantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Por segunda vez, el Mandatario potosino Ricardo Gallardo Cardona dirige la Mesa de Coordinaci\u00f3n para la Construcci\u00f3n de la Paz en Venado &nbsp; Venado, San Luis Potos\u00ed.- La puesta en marcha del Mando Policial Coordinado, recientemente formalizado con el respaldo de todas y todos &hellip; <\/p>\n","protected":false},"author":1,"featured_media":81724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4],"tags":[],"class_list":["post-81723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/81723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=81723"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/81723\/revisions"}],"predecessor-version":[{"id":81725,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/81723\/revisions\/81725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/81724"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=81723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=81723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=81723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}