{"id":89982,"date":"2023-11-09T06:41:57","date_gmt":"2023-11-09T12:41:57","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=89982"},"modified":"2023-11-09T06:41:57","modified_gmt":"2023-11-09T12:41:57","slug":"concluye-temporada-de-incendios-con-excelentes-resultados-segam","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/concluye-temporada-de-incendios-con-excelentes-resultados-segam\/","title":{"rendered":"Concluye temporada de incendios con excelentes resultados: SEGAM"},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>San Luis Potos\u00ed ya despeg\u00f3 en la prevenci\u00f3n, control y extinci\u00f3n de incendios forestales, al colocarse entre los tres Estados con menos afectaciones a nivel nacional<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Durante el 2023, San Luis Potos\u00ed registr\u00f3 31 incendios forestales con 473 hect\u00e1reas afectadas, con lo que ya despeg\u00f3 en la prevenci\u00f3n, control y extinci\u00f3n de estos fen\u00f3menos, al posicionarse entre los tres Estados menos afectados a nivel nacional, logro que refleja la eficacia de las estrategias estatales implementadas, inform\u00f3 la Secretar\u00eda de Ecolog\u00eda y Gesti\u00f3n Ambiental (Segam).<\/p>\n<p>Durante \u00faltima sesi\u00f3n del Comit\u00e9 Estatal de Manejo de Fuego, el titular de la dependencia estatal, Jes\u00fas Emmanuel Ramos Hern\u00e1ndez, mencion\u00f3 que para el Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, es de suma importancia la coordinaci\u00f3n y cooperaci\u00f3n para superar la temporada de incendios y reconoci\u00f3 la respuesta inmediata y efectiva de las y los voluntarios, autoridades estatales y federales, as\u00ed como la colaboraci\u00f3n de diversas dependencias.<\/p>\n<p>En la \u00faltima sesi\u00f3n del Comit\u00e9, se reconoci\u00f3 la colaboraci\u00f3n y el compromiso de todas y todos quienes desempe\u00f1aron un papel fundamental en la gesti\u00f3n de incendios forestales en el Estado, lo que logr\u00f3 minimizar los da\u00f1os y proteger el patrimonio natural de San Luis Potos\u00ed, \u201ccon estos resultados se refuerza su compromiso de seguir trabajando en la preservaci\u00f3n y el cuidado de nuestros recursos naturales, asegurando un futuro sostenible\u201d, finaliz\u00f3 Ramos Hern\u00e1ndez.<\/p>\n<p>La reuni\u00f3n se llev\u00f3 a cabo en la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos (Sedarh), al que acudieron Teodoro Morales Organista, titular de la Promotora de Desarrollo Forestal en San Luis Potos\u00ed de la Comisi\u00f3n Nacional Forestal (Conafor); Mauricio Ordaz Flores, director de la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC); adem\u00e1s de representantes de la Universidad Aut\u00f3noma de San Luis Potos\u00ed (UASLP) y de la Secretar\u00eda de la Defensa Nacional (Sedena).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 &nbsp; San Luis Potos\u00ed ya despeg\u00f3 en la prevenci\u00f3n, control y extinci\u00f3n de incendios forestales, al colocarse entre los tres Estados con menos afectaciones a nivel nacional &nbsp; Durante el 2023, San Luis Potos\u00ed registr\u00f3 31 incendios forestales con 473 hect\u00e1reas afectadas, con lo &hellip; <\/p>\n","protected":false},"author":1,"featured_media":89983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,12,5],"tags":[],"class_list":["post-89982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-nacional","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/89982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=89982"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/89982\/revisions"}],"predecessor-version":[{"id":89984,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/89982\/revisions\/89984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/89983"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=89982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=89982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=89982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}