{"id":90028,"date":"2023-11-10T06:34:29","date_gmt":"2023-11-10T12:34:29","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=90028"},"modified":"2023-11-10T06:34:29","modified_gmt":"2023-11-10T12:34:29","slug":"ricardo-gallardo-inaugura-competencias-del-nacional-charro-2023","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/ricardo-gallardo-inaugura-competencias-del-nacional-charro-2023\/","title":{"rendered":"Ricardo Gallardo inaugura competencias del nacional charro 2023"},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Se espera una derrama econ\u00f3mica de m\u00e1s de 200 millones de pesos, en este evento que se realizar\u00e1 del 9 de noviembre al 3 de diciembre<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Este jueves, el Gobernador Ricardo Gallardo Cardona inaugur\u00f3 el LXXIX Congreso y Campeonato Nacional Charro San Luis Potos\u00ed 2023, en el que se espera una derrama econ\u00f3mica de m\u00e1s de 200 millones de pesos, que va a generar este evento que se realizar\u00e1 del 9 de noviembre al 3 de diciembre.<\/p>\n<p>En este Campeonato se espera la participaci\u00f3n de 6 mil atletas de 228 equipos de charros, 168 de escaramuza y 16 charros completos, quienes demostrar\u00e1n con destreza las suertes que conforman esta disciplina para conseguir el m\u00e1ximo premio.<\/p>\n<p>En su mensaje, ante charros, escaramuzas y el p\u00fablico asistente, Gallardo Cardona refrend\u00f3 su compromiso de seguir impulsando eventos de todo tipo que permitan generar derrama econ\u00f3mica donde no suele realizarse otra actividad.<\/p>\n<p>Gallardo Cardona destac\u00f3 la importancia de brindar apoyo a deportes que realzan la identidad nacional y que a la vez aumentan el n\u00famero practicante de la charrer\u00eda. Adem\u00e1s de que proyecta a San Luis Potos\u00ed a nivel nacional e internacional tur\u00edsticamente, ya que muchas personas que asisten a la capital, ya tienen reservados algunos d\u00edas para conocer las cuatro regiones del Estado, lo que detona el desarrollo de los 58 municipios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 &nbsp; Se espera una derrama econ\u00f3mica de m\u00e1s de 200 millones de pesos, en este evento que se realizar\u00e1 del 9 de noviembre al 3 de diciembre &nbsp; Este jueves, el Gobernador Ricardo Gallardo Cardona inaugur\u00f3 el LXXIX Congreso y Campeonato Nacional Charro San &hellip; <\/p>\n","protected":false},"author":1,"featured_media":90029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,12,5],"tags":[],"class_list":["post-90028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-nacional","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=90028"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90028\/revisions"}],"predecessor-version":[{"id":90030,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90028\/revisions\/90030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/90029"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=90028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=90028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=90028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}