{"id":90135,"date":"2023-11-14T08:08:58","date_gmt":"2023-11-14T14:08:58","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=90135"},"modified":"2023-11-14T08:08:58","modified_gmt":"2023-11-14T14:08:58","slug":"vinos-potosinos-captaran-mercado-mundial-ricardo-gallardo","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/vinos-potosinos-captaran-mercado-mundial-ricardo-gallardo\/","title":{"rendered":"Vinos potosinos captar\u00e1n mercado mundial: Ricardo Gallardo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>El Gobernador del Estado instala el Consejo Vitivin\u00edcola, donde fij\u00f3 como meta la exportaci\u00f3n mundial de los productos potosinos y el despegue del patrimonio cultural y econ\u00f3mico que representa esta actividad productiva.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Para impulsar el cultivo sostenible y sustentable de la vid y el vino en el Estado, el Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona, instal\u00f3 el Consejo Vitivin\u00edcola Estatal, organismo de consulta y apoyo que permitir\u00e1 el despegue de esta actividad econ\u00f3mica, donde fij\u00f3 como meta promover los productos potosinos en todo el mundo, trazar rutas para su exportaci\u00f3n a los mejores restaurantes, hoteles y paladares, adem\u00e1s de fortalecer la difusi\u00f3n a nivel nacional e internacional.<\/p>\n<p>Al tomar la protesta a dicho Consejo, conforme lo dicta la Ley Vitivin\u00edcola, el Mandatario Estatal, resalt\u00f3 que ya se comenz\u00f3 el trabajo de promoci\u00f3n a trav\u00e9s de embajadas, para hacer sinergia por los vinos potosinos, con el apoyo de las Secretar\u00edas de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos (Sedarh) y de Desarrollo Econ\u00f3mico del Estado (Sedeco).<\/p>\n<p>Gallardo Cardona coment\u00f3 que con el apoyo de su Gobierno se impulsar\u00e1 una vitivinicultura respetuosa con el ambiente, sostenible y que contribuya al desarrollo social y econ\u00f3mico de las empresas familiares productoras y los grupos ejidales interesados en darle identidad y reforzar el patrimonio cultural vin\u00edcola en el Estado.<\/p>\n<p>Forman parte del Consejo: la y el titular de Sedarh y Sedeco; presidentes municipales de Guadalc\u00e1zar, Moctezuma, Rioverde, Soledad de Graciano S\u00e1nchez; representantes de las empresas Ron Potos\u00ed, Cava Quintanilla, Vin\u00edcola Pozo de Luna, Villa Cordelia, Vi\u00f1edo Vi\u00f1alc\u00e1zar y La Malanca, entre otros, quienes propondr\u00e1n acciones para el cumplimiento de la Ley, contribuir\u00e1n a los trabajos de certificaci\u00f3n de productores, y la promoci\u00f3n de los productos potosinos con certificaci\u00f3n, as\u00ed como el Enoturismo, un tipo de turismo enfocado en las zonas de producci\u00f3n de vino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El Gobernador del Estado instala el Consejo Vitivin\u00edcola, donde fij\u00f3 como meta la exportaci\u00f3n mundial de los productos potosinos y el despegue del patrimonio cultural y econ\u00f3mico que representa esta actividad productiva. &nbsp; Para impulsar el cultivo sostenible y sustentable de la vid y &hellip; <\/p>\n","protected":false},"author":1,"featured_media":90136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,12,5],"tags":[],"class_list":["post-90135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-nacional","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=90135"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90135\/revisions"}],"predecessor-version":[{"id":90137,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90135\/revisions\/90137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/90136"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=90135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=90135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=90135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}