{"id":90177,"date":"2023-11-15T07:12:57","date_gmt":"2023-11-15T13:12:57","guid":{"rendered":"http:\/\/amanecerhuasteco.com\/portal\/?p=90177"},"modified":"2023-11-15T07:12:57","modified_gmt":"2023-11-15T13:12:57","slug":"ricardo-gallardo-sostiene-reunion-con-consul-de-japon","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/ricardo-gallardo-sostiene-reunion-con-consul-de-japon\/","title":{"rendered":"Ricardo Gallardo sostiene reuni\u00f3n con c\u00f3nsul de Jap\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><strong>Al encuentro donde tambi\u00e9n asistieron directivos de Daikin, el Gobernador refrend\u00f3 su apoyo para consolidar la correcta instalaci\u00f3n de la planta.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>El Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona, sostuvo un encuentro con el C\u00f3nsul General de Jap\u00f3n en Le\u00f3n, Katsumi Itagak, los directivos de la empresa Daikin, donde se dieron a conocer los avances de la instalaci\u00f3n de la empresa y solicitar al Gobernador las gestiones ante distintas estancias federales y municipales para el correcto proceso de instalaci\u00f3n de la empresa.<\/p>\n<p>\u00abNosotros nos comprometemos a que la empresa est\u00e9 en funcionamiento en el tiempo establecido, cuentan con todo nuestro apoyo\u00bb, afirm\u00f3 el Jefe del Ejecutivo Estatal, quien destac\u00f3 que San Luis Potos\u00ed ya despeg\u00f3 hacia el crecimiento econ\u00f3mico, pues puntualiz\u00f3 que la instalaci\u00f3n de esta compa\u00f1\u00eda representa una inversi\u00f3n de 300 millones de d\u00f3lares y cerca de 4 mil empleos.<\/p>\n<p>Por su parte, el C\u00f3nsul de Jap\u00f3n, Katsumi Itagak, agradeci\u00f3 al Gobernador potosino, la enorme disposici\u00f3n para potencializar el avance de la instalaci\u00f3n de las dos nuevas plantas de Daikin; destac\u00f3 que, el compromiso para gestionar ante instancias de otros niveles de Gobierno la correcta instalaci\u00f3n de la compa\u00f1\u00eda, otorga mucha confianza entre los directivos para arrancar la producci\u00f3n hacia los primeros meses del 2024.<\/p>\n<p>Reconoci\u00f3 el trabajo de la administraci\u00f3n de Ricardo Gallardo para abrir las puertas de la Entidad hacia la comunidad japonesa y hacia los inversionistas para facilitar el desarrollo de proyectos en beneficio de ambos pueblos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Al encuentro donde tambi\u00e9n asistieron directivos de Daikin, el Gobernador refrend\u00f3 su apoyo para consolidar la correcta instalaci\u00f3n de la planta. &nbsp; El Gobernador de San Luis Potos\u00ed Ricardo Gallardo Cardona, sostuvo un encuentro con el C\u00f3nsul General de Jap\u00f3n en Le\u00f3n, Katsumi Itagak, &hellip; <\/p>\n","protected":false},"author":1,"featured_media":90178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,4,12,5],"tags":[],"class_list":["post-90177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-estado","category-inicio","category-nacional","category-politica"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=90177"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90177\/revisions"}],"predecessor-version":[{"id":90179,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/90177\/revisions\/90179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/90178"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=90177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=90177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=90177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}