{"id":97483,"date":"2024-07-20T07:55:37","date_gmt":"2024-07-20T13:55:37","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=97483"},"modified":"2024-07-20T07:55:39","modified_gmt":"2024-07-20T13:55:39","slug":"avanza-mejora-de-vialidades-interestatales-en-slp","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/avanza-mejora-de-vialidades-interestatales-en-slp\/","title":{"rendered":"Avanza mejora de vialidades interestatales en SLP"},"content":{"rendered":"\n<p><br>\u2022 En coordinaci\u00f3n con la JEC, la Secretar\u00eda General de Gobierno supervisa avances en obras que actualmente est\u00e1n en proceso en las cuatro regiones<\/p>\n\n\n\n<p>En cumplimiento a la instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona, de brindar mejores condiciones de bienestar en apoyo a las familias potosinas, la Secretar\u00eda General de Gobierno (SGG) en coordinaci\u00f3n con las diferentes dependencias estatales supervisa las obras y acciones que la administraci\u00f3n impulsa en las cuatro regiones.<br>As\u00ed lo inform\u00f3 el secretario general de Gobierno, J. Guadalupe Torres S\u00e1nchez, quien sostuvo una reuni\u00f3n con el director de la Junta Estatal de Caminos (JEC), Francisco Reyes Novelo, para dar seguimiento a la apertura de los dos puentes vehiculares de la carretera Cerritos-Tula.<br>Detall\u00f3 que la administraci\u00f3n estatal supervisa que se realice con materiales de calidad y prev\u00e9n que la obra sea entregada en agosto. \u201cDe acuerdo con la empresa que realiza la obra, en breve ambos puentes estar\u00e1n funcionando\u201d, dijo.<br>Como resultado de esta reuni\u00f3n, Torres S\u00e1nchez solicit\u00f3 al titular de la JEC a seguir fortaleciendo la atenci\u00f3n y rehabilitaci\u00f3n de caminos, mediante acciones como limpieza, sobre todo en esta temporada de lluvia para garantizar traslados \u00e1giles, c\u00f3modos y seguros a quienes transitan por caminos y carreteras del Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 En coordinaci\u00f3n con la JEC, la Secretar\u00eda General de Gobierno supervisa avances en obras que actualmente est\u00e1n en proceso en las cuatro regiones En cumplimiento a la instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona, de brindar mejores condiciones de bienestar en apoyo a las familias &hellip; <\/p>\n","protected":false},"author":1,"featured_media":97484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,7,22,56,11,55,4,44,60,30,31,59,42,21,53,20,58,57,43,32],"tags":[],"class_list":["post-97483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquismon","category-ciudad","category-ebano","category-el-naranjo","category-estado","category-guadalcazar","category-inicio","category-matehuala","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamasopo","category-tamazunchale","category-tamuin","category-tancanhuitz","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=97483"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97483\/revisions"}],"predecessor-version":[{"id":97485,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97483\/revisions\/97485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/97484"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=97483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=97483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=97483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}