{"id":97619,"date":"2024-07-25T07:09:48","date_gmt":"2024-07-25T13:09:48","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=97619"},"modified":"2024-07-25T07:09:50","modified_gmt":"2024-07-25T13:09:50","slug":"pce-atiende-afectaciones-por-lluvias-en-matehuala","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/pce-atiende-afectaciones-por-lluvias-en-matehuala\/","title":{"rendered":"PCE atiende afectaciones por lluvias en Matehuala"},"content":{"rendered":"\n<p><br>\u2022\u00a0 \u00a0 \u00a0 \u00a0Autoridades municipales reportaron a la dependencia estatal solo da\u00f1os materiales\u00a0<\/p>\n\n\n\n<p>La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC) inform\u00f3 que de manera inmediata brind\u00f3 apoyo a las y los habitantes de Matehuala, debido a las inundaciones ocasionadas por las lluvias.<br>El director de Protecci\u00f3n Civil Estatal, Mauricio Ordaz Flores, detall\u00f3 que personal de la dependencia brind\u00f3 auxilio y puso a salvo a ni\u00f1as, ni\u00f1os madres y padres de familia, as\u00ed como a personal de la guarder\u00eda Mi Granjita quienes quedaron atrapados luego de que los niveles de agua incrementaron en la colonia Fidel Vel\u00e1zquez, donde se ubica este centro infantil.<br>Adem\u00e1s, se tuvieron seis veh\u00edculos varados en diferentes puntos de la cabecera municipal, sin personas lesionadas, solo da\u00f1os materiales.<br>Agreg\u00f3 que autoridades de Matehuala informaron a la CEPC que al momento se presentan lluvias intermitentes, pero la situaci\u00f3n no es grave; sin embargo, la dependencia estatal mantendr\u00e1 el monitoreo para actuar en caso de ser necesario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022\u00a0 \u00a0 \u00a0 \u00a0Autoridades municipales reportaron a la dependencia estatal solo da\u00f1os materiales\u00a0 La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC) inform\u00f3 que de manera inmediata brind\u00f3 apoyo a las y los habitantes de Matehuala, debido a las inundaciones ocasionadas por las lluvias.El director de Protecci\u00f3n &hellip; <\/p>\n","protected":false},"author":1,"featured_media":97620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,7,56,11,55,4,44,10,12,60,30,31,59,42,21,53,20,57,43],"tags":[],"class_list":["post-97619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquismon","category-ciudad","category-el-naranjo","category-estado","category-guadalcazar","category-inicio","category-matehuala","category-municipios","category-nacional","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamasopo","category-tamazunchale","category-tamuin","category-tanlajas","category-villa-de-reyes"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=97619"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97619\/revisions"}],"predecessor-version":[{"id":97621,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97619\/revisions\/97621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/97620"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=97619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=97619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=97619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}