{"id":97634,"date":"2024-07-25T07:25:31","date_gmt":"2024-07-25T13:25:31","guid":{"rendered":"https:\/\/amanecerhuasteco.com\/portal\/?p=97634"},"modified":"2024-07-25T07:25:33","modified_gmt":"2024-07-25T13:25:33","slug":"la-fenapo-sera-una-de-las-ferias-mas-seguras-del-pais-sspce","status":"publish","type":"post","link":"https:\/\/amanecerhuasteco.com\/portal\/la-fenapo-sera-una-de-las-ferias-mas-seguras-del-pais-sspce\/","title":{"rendered":"La FENAPO ser\u00e1 una de las ferias m\u00e1s seguras del pa\u00eds: SSPCE"},"content":{"rendered":"\n<p><br>Con la colaboraci\u00f3n de autoridades de los tres \u00f3rdenes de Gobierno, est\u00e1 garantizada la salvaguarda de la integridad y patrimonio de las y los asistentes<\/p>\n\n\n\n<p>La Feria Nacional Potosina (Fenapo), ser\u00e1 una de las m\u00e1s seguras del pa\u00eds, con una cobertura total de prevenci\u00f3n y vigilancia ante las proyecciones de asistencia r\u00e9cord en sus instalaciones, asegur\u00f3 el titular de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana del Estado (SSPCE), Jos\u00e9 Luis Ruiz Contreras, durante la tercera reuni\u00f3n estrat\u00e9gica del Plan de Operaciones Fenapo 2024.<br>Detall\u00f3 que el Plan de Operaciones Fenapo 2024 que estar\u00e1 activo del 8 de agosto al 1 de septiembre, con m\u00e1s de 200 oficiales de la Guardia Civil Estatal (GCE) y sus diversos agrupamientos, aunado al apoyo de cerca de 200 alumnas y alumnos de la tercera generaci\u00f3n de la GCE, m\u00e1s de 50 agentes de la Divisi\u00f3n Caminos y las unidades especializadas \u201cPotros\u201d, lo anterior complementado con el apoyo de modernas torres de videovigilancia, las c\u00e1maras de seguridad que operan desde el C5i2 y sobrevuelos a trav\u00e9s de drones.<br>La cobertura abarca la totalidad de las instalaciones al interior y exterior, as\u00ed como la valiosa colaboraci\u00f3n de seguridad p\u00fablica municipal de la capital y Soledad de Graciano S\u00e1nchez. De igual forma, el personal de Guardia Nacional, la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC) y municipal, Fiscal\u00eda General del Estado, el cuerpo de bomberos, param\u00e9dicos y rescatistas y seguridad privada.<br>Se llevar\u00e1n a cabo reuniones peri\u00f3dicas entre las distintas autoridades involucradas para monitorear y dar seguimiento al desarrollo de este evento y, con base en ello, realizar los ajustes necesarios, para alcanzar un saldo blanco en esta edici\u00f3n en la que se esperan ocho millones de visitas.<br>Agreg\u00f3 que de manera simult\u00e1nea operan los dispositivos, Vacaciones Seguras 2024 y Caminos Seguros, para brindar paz y tranquilidad a miles de visitantes, turistas nacionales, extranjeros y connacionales provenientes de Estados Unidos, en las cuatro regiones de la Entidad y sus caminos y carreteras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la colaboraci\u00f3n de autoridades de los tres \u00f3rdenes de Gobierno, est\u00e1 garantizada la salvaguarda de la integridad y patrimonio de las y los asistentes La Feria Nacional Potosina (Fenapo), ser\u00e1 una de las m\u00e1s seguras del pa\u00eds, con una cobertura total de prevenci\u00f3n y &hellip; <\/p>\n","protected":false},"author":1,"featured_media":97635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,7,22,56,11,55,4,44,10,12,60,30,31,59,42,21,53,20,58,57,43,32],"tags":[],"class_list":["post-97634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aquismon","category-ciudad","category-ebano","category-el-naranjo","category-estado","category-guadalcazar","category-inicio","category-matehuala","category-municipios","category-nacional","category-rayon","category-rioverde","category-sanluispotosi","category-santa-catarina","category-soledad","category-tamasopo","category-tamazunchale","category-tamuin","category-tancanhuitz","category-tanlajas","category-villa-de-reyes","category-xilitla"],"_links":{"self":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/comments?post=97634"}],"version-history":[{"count":1,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97634\/revisions"}],"predecessor-version":[{"id":97636,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/posts\/97634\/revisions\/97636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media\/97635"}],"wp:attachment":[{"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/media?parent=97634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/categories?post=97634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amanecerhuasteco.com\/portal\/wp-json\/wp\/v2\/tags?post=97634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}